{"id":960,"date":"2022-04-11T08:05:51","date_gmt":"2022-04-11T08:05:51","guid":{"rendered":"https:\/\/sowax.fr\/home\/"},"modified":"2024-08-30T04:17:07","modified_gmt":"2024-08-30T04:17:07","slug":"inicio","status":"publish","type":"page","link":"https:\/\/sowax.fr\/es\/","title":{"rendered":"Accueil"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"960\" class=\"elementor elementor-960 elementor-10\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-51587da elementor-section-full_width elementor-section-height-full elementor-section-height-default elementor-section-items-middle elementor-invisible\" data-id=\"51587da\" data-element_type=\"section\" id=\"intro\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b59e56b\" data-id=\"b59e56b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-8a8e67c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8a8e67c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-d96585f\" data-id=\"d96585f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-b9d2dad header-slider elementor-hidden-tablet elementor-hidden-mobile elementor--h-position-center elementor--v-position-middle elementor-arrows-position-inside elementor-pagination-position-inside elementor-widget elementor-widget-slides\" data-id=\"b9d2dad\" data-element_type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;transition&quot;:&quot;slide&quot;,&quot;transition_speed&quot;:500}\" data-widget_type=\"slides.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t<div class=\"elementor-slides-wrapper elementor-main-swiper swiper\" dir=\"ltr\" data-animation=\"fadeInUp\">\n\t\t\t\t<div class=\"swiper-wrapper elementor-slides\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-repeater-item-6aac38f swiper-slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-heading\"><h1 style=\"text-shadow: 2px 2px 4px #000;\">Especialista en la protecci\u00f3n<br>de los veh\u00edculos y maquinaria industrial<br>contra la corrosi\u00f3n.<\/h1><\/div><div class=\"elementor-slide-description\"><h5 style=\"font-family: Montserrat, sans-serif; font-weight: 200;\">Fabricantes y concesionarios de autom\u00f3viles <br>y de la  industrial en general, \u00a1WAX PRO est\u00e1 hecho para ti!\n<\/div><a href=\"#featured-services\" class=\"elementor-button elementor-slide-button elementor-size-sm\">Comience su visita<\/a><\/div><\/div><\/div><div class=\"elementor-repeater-item-963d42f swiper-slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-heading\"><span style=\"text-shadow: 2px 2px 5px #000;\">Exclusivamente de profesionales<br>para profesionales<\/span><\/div><div class=\"elementor-slide-description\"><h5 style=\"font-family: Montserrat, sans-serif; font-weight: 200;\">Fabricantes y concesionarios de autom\u00f3viles <br>y de la  industrial en general, \u00a1WAX PRO est\u00e1 hecho para ti!<\/div><a href=\"#featured-services\" class=\"elementor-button elementor-slide-button elementor-size-sm\">Comience su visita<\/a><\/div><\/div><\/div><div class=\"elementor-repeater-item-d8224b3 swiper-slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-heading\"><span style=\"text-shadow: 2px 2px 5px #000;\">Wax Pro B Power Protection<\/span><\/div><div class=\"elementor-slide-description\"><h5 style=\"font-family: Montserrat, sans-serif; font-weight: 200;\">El concepto de B Power Protection permite<br>\nuna protecci\u00f3n muy eficaz de la pintura de su<br>\ncoche al crear un escudo de alto brillo.<\/h5><\/div><a href=\"#treatments\" class=\"elementor-button elementor-slide-button elementor-size-sm\">Descubra nuestros tratamientos<\/a><\/div><\/div><\/div><div class=\"elementor-repeater-item-6138c95 swiper-slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-heading\"><span style=\"text-shadow: 2px 2px 5px #000;\">Wax Pro B Power Protection Moto<\/span><\/div><div class=\"elementor-slide-description\"><h5 style=\"font-family: Montserrat, sans-serif; font-weight: 200;\">Nuestro concepto Wax Pro B Power Protection Moto<br>permite una protecci\u00f3n ultraefectiva de la<br>pintura de su moto al crear un escudo de protecci\u00f3n de alto brillo.<\/h5><\/div><a href=\"#treatments\" class=\"elementor-button elementor-slide-button elementor-size-sm\">Descubra nuestros tratamientos<\/a><\/div><\/div><\/div><div class=\"elementor-repeater-item-cc28d93 swiper-slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-heading\"><span style=\"text-shadow: 2px 2px 5px #000;\">Sellado de pintura de<br>alto brillo<\/span><\/div><div class=\"elementor-slide-description\"><h5 style=\"font-family: Montserrat, sans-serif; font-weight: 200;\">Nuestros tratamientos proporcionan a la capa de pintura de los autom\u00f3viles, <br \/>un escudo de alto brillo pr\u00e1cticamente inviolable<\/h5><\/div><a href=\"#treatments\" class=\"elementor-button elementor-slide-button elementor-size-sm\">Descubra nuestros tratamientos<\/a><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t\t<span class=\"elementor-screen-only\">Diapositiva anterior<\/span>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t\t<span class=\"elementor-screen-only\">Diapositiva siguiente<\/span>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1708f92 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1708f92\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4d9a3c7\" data-id=\"4d9a3c7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fdd0f42 header-slider slider-mobile elementor-hidden-desktop elementor-hidden-tablet elementor--h-position-center elementor--v-position-middle elementor-arrows-position-inside elementor-pagination-position-inside elementor-widget elementor-widget-slides\" data-id=\"fdd0f42\" data-element_type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;transition&quot;:&quot;slide&quot;,&quot;transition_speed&quot;:500}\" data-widget_type=\"slides.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t<div class=\"elementor-slides-wrapper elementor-main-swiper swiper\" dir=\"ltr\" data-animation=\"fadeInUp\">\n\t\t\t\t<div class=\"swiper-wrapper elementor-slides\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-repeater-item-6aac38f swiper-slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-heading\"><h1 style=\"text-shadow: 2px 2px 4px #000;\">Especialista en <br>la protecci\u00f3n de<br> los veh\u00edculos y<br> maquinaria<br>industrial contra<br> la corrosi\u00f3n.<\/h1><\/div><div class=\"elementor-slide-description\"><h5 style=\"font-family: Montserrat, sans-serif; font-weight: 200;\">Fabricantes y concesionarios de <br>autom\u00f3viles y de la  industrial en general,<br> \u00a1WAX PRO est\u00e1 hecho para ti!\n<\/div><a href=\"#featured-services\" class=\"elementor-button elementor-slide-button elementor-size-sm\">Comience su visita<\/a><\/div><\/div><\/div><div class=\"elementor-repeater-item-963d42f swiper-slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-heading\"><span style=\"text-shadow: 2px 2px 5px #000;\">Exclusivamente <br>de profesionales<br>para <br>profesionales<\/span><\/div><div class=\"elementor-slide-description\"><h5 style=\"font-family: Montserrat, sans-serif; font-weight: 200;\">Fabricantes y concesionarios de <br>autom\u00f3viles y de la  industrial en general,<br> \u00a1WAX PRO est\u00e1 hecho para ti!<\/div><a href=\"#featured-services\" class=\"elementor-button elementor-slide-button elementor-size-sm\">Comience su visita<\/a><\/div><\/div><\/div><div class=\"elementor-repeater-item-d8224b3 swiper-slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-heading\"><span style=\"text-shadow: 2px 2px 5px #000;\">Wax Pro B Power<br>Protection<\/span><\/div><div class=\"elementor-slide-description\"><h5 style=\"font-family: Montserrat, sans-serif; font-weight: 200;\">El concepto de B Power Protection<br>permite\nuna protecci\u00f3n muy eficaz<br>de la pintura de su\ncoche<br>al crear un escudo de alto brillo.<\/h5><\/div><a href=\"#treatments\" class=\"elementor-button elementor-slide-button elementor-size-sm\">Descubra nuestro tratamiento<\/a><\/div><\/div><\/div><div class=\"elementor-repeater-item-2179f49 swiper-slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-heading\"><span style=\"text-shadow: 2px 2px 5px #000;\">Wax Pro B Power <br>Protection Moto<\/span><\/div><div class=\"elementor-slide-description\"><h5 style=\"font-family: Montserrat, sans-serif; font-weight: 200;\">Nuestro concepto Wax Pro B Power <br>Protection Moto permite una protecci\u00f3n<br> ultraefectiva de la\npintura de su moto  al<br>crear un escudo de protecci\u00f3n de alto brillo.<\/h5><\/div><a href=\"#treatments\" class=\"elementor-button elementor-slide-button elementor-size-sm\">Descubra nuestro tratamiento<\/a><\/div><\/div><\/div><div class=\"elementor-repeater-item-cc28d93 swiper-slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-heading\"><span style=\"text-shadow: 2px 2px 5px #000;\">Sellado de <br>pintura de <br> alto brillo<\/span><\/div><div class=\"elementor-slide-description\"><h5 style=\"font-family: Montserrat, sans-serif; font-weight: 200;\">Nuestros tratamientos proporcionan<br> a la capa de pintura de los <br> autom\u00f3viles, un escudo de alto brillo<br>pr\u00e1cticamente inviolable<\/h5><\/div><a href=\"#treatments\" class=\"elementor-button elementor-slide-button elementor-size-sm\">Descubra nuestro tratamiento<\/a><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t\t<span class=\"elementor-screen-only\">Diapositiva anterior<\/span>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t\t<span class=\"elementor-screen-only\">Diapositiva siguiente<\/span>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-94ec73e elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"94ec73e\" data-element_type=\"section\" id=\"featured-services\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-81ee2e6\" data-id=\"81ee2e6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b0056e1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b0056e1\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-ad2c522\" data-id=\"ad2c522\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-667c3ef elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"667c3ef\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-warehouse\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-34246dc elementor-widget elementor-widget-heading\" data-id=\"34246dc\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Fabricantes de autom\u00f3viles<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-99fbd25 elementor-widget elementor-widget-text-editor\" data-id=\"99fbd25\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Desde la carrocer\u00eda hasta el chasis, desde el interior hasta el motor, tratamos los veh\u00edculos con WAX PRO desde la l\u00ednea de ensamblaje hasta la salida de la f\u00e1brica. <strong><a href=\"https:\/\/sowax.fr\/es\/#contact\" data-wplink-edit=\"true\">Cont\u00e1ctenos<\/a> <\/strong>para encontrar la soluci\u00f3n adecuada.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-56f821f\" data-id=\"56f821f\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-62d8d4c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"62d8d4c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-071e279\" data-id=\"071e279\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0a669b4 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"0a669b4\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-store\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4a29e8b elementor-widget elementor-widget-heading\" data-id=\"4a29e8b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Grupos automovil\u00edsticos<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-df267c0 elementor-widget elementor-widget-text-editor\" data-id=\"df267c0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>A\u00f1adimos valor a los servicios de los concesionarios, revendedores y comerciantes de veh\u00edculos usados. P\u00f3ngase <a href=\"https:\/\/sowax.fr\/es\/#contact\"><strong>en contacto<\/strong><\/a> con nosotros para ofrecer a sus clientes el mejor servicio posible.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-0e19c91\" data-id=\"0e19c91\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e8b0cdf elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e8b0cdf\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-6280d08\" data-id=\"6280d08\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8199e8a elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"8199e8a\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-industry\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d8d54cf elementor-widget elementor-widget-heading\" data-id=\"d8d54cf\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Industria general<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-12c9e69 elementor-widget elementor-widget-text-editor\" data-id=\"12c9e69\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Como l\u00edderes en los campos de la aeron\u00e1utica, la ingenier\u00eda civil, la carrocer\u00eda industrial y el transporte, le ofrecemos la soluci\u00f3n para evitar la corrosi\u00f3n. P\u00f3ngase <a href=\"https:\/\/sowax.fr\/es\/#contact\"><strong>en contacto<\/strong><\/a> con nosotros para un asesoramiento personalizado.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9fe14ee elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9fe14ee\" data-element_type=\"section\" id=\"missions\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8f398f7\" data-id=\"8f398f7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0b74973 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"0b74973\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">LAS MISIONES DE WAX PRO SOFDI <\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e372fe2 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"e372fe2\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Las lluvias \u00e1cidas, la radiaci\u00f3n solar y el aire salino son elementos da\u00f1inos que afectan cada vez m\u00e1s <strong>al estado de las m\u00e1quinas y veh\u00edculos<\/strong>. A medida que la regulaci\u00f3n proh\u00edbe el uso de solventes, debilitando nuestras pinturas, los requisitos de durabilidad y <strong>resistencia a los incidentes meteorol\u00f3gicos de los materiales modernos<\/strong> han aumentado significativamente, ya sea en <strong>tierra<\/strong>, <strong>mar<\/strong> o <strong>aire<\/strong>. WAX PRO satisface estas demandas con productos exclusivos, tratamientos y programas dise\u00f1ados espec\u00edficamente para abordar estas restricciones.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e494105 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e494105\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bec3e35\" data-id=\"bec3e35\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-05e8c36 elementor-widget elementor-widget-spacer\" data-id=\"05e8c36\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6827a6e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6827a6e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-37aec23\" data-id=\"37aec23\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b8b7025 elementor-widget elementor-widget-heading\" data-id=\"b8b7025\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-medium\">Nuestras soluciones de protecci\u00f3n y mantenimiento para autom\u00f3viles<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-db3df4a\" data-id=\"db3df4a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2e406c6 elementor-widget elementor-widget-heading\" data-id=\"2e406c6\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-medium\">Nuestras soluciones de protecci\u00f3n y mantenimiento para la industria<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b18eb63 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b18eb63\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2ca3076\" data-id=\"2ca3076\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7457169 elementor-widget elementor-widget-image\" data-id=\"7457169\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/sowax.fr\/wp-content\/uploads\/2023\/11\/auto-moto-1.png\" class=\"attachment-large size-large wp-image-9071\" alt=\"\" srcset=\"https:\/\/sowax.fr\/wp-content\/uploads\/2023\/11\/auto-moto-1.png 1024w, https:\/\/sowax.fr\/wp-content\/uploads\/2023\/11\/auto-moto-1-300x300.png 300w, https:\/\/sowax.fr\/wp-content\/uploads\/2023\/11\/auto-moto-1-150x150.png 150w, https:\/\/sowax.fr\/wp-content\/uploads\/2023\/11\/auto-moto-1-768x768.png 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-f32140f\" data-id=\"f32140f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-626fa63 elementor-widget elementor-widget-image\" data-id=\"626fa63\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/sowax.fr\/wp-content\/uploads\/2023\/11\/Auto_Industriel-1.png\" class=\"attachment-large size-large wp-image-9075\" alt=\"\" srcset=\"https:\/\/sowax.fr\/wp-content\/uploads\/2023\/11\/Auto_Industriel-1.png 1024w, https:\/\/sowax.fr\/wp-content\/uploads\/2023\/11\/Auto_Industriel-1-300x300.png 300w, https:\/\/sowax.fr\/wp-content\/uploads\/2023\/11\/Auto_Industriel-1-150x150.png 150w, https:\/\/sowax.fr\/wp-content\/uploads\/2023\/11\/Auto_Industriel-1-768x768.png 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b228d31 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b228d31\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-44a2ce5\" data-id=\"44a2ce5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3ca6f7c elementor-widget elementor-widget-spacer\" data-id=\"3ca6f7c\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5a1386a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5a1386a\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-39cc840\" data-id=\"39cc840\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dc93d0a elementor-testimonial--layout-image_stacked elementor-testimonial--skin-default elementor-testimonial--align-center elementor-arrows-yes elementor-pagination-type-bullets elementor-widget elementor-widget-testimonial-carousel\" data-id=\"dc93d0a\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_scroll&quot;:&quot;1&quot;,&quot;show_arrows&quot;:&quot;yes&quot;,&quot;pagination&quot;:&quot;bullets&quot;,&quot;speed&quot;:500,&quot;autoplay&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;loop&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;space_between&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]}}\" data-widget_type=\"testimonial-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t<div class=\"elementor-main-swiper swiper\">\n\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial__image\">\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/sowax.fr\/wp-content\/uploads\/2023\/11\/Camion-scaled-1.jpg\" alt=\"Protecci\u00f3n completa contra la corrosi\u00f3n para la industria\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Protecci\u00f3n completa contra la corrosi\u00f3n para la industria<\/span><span class=\"elementor-testimonial__title\"><p>Nuestras soluciones le ofrecen una defensa activa y duradera contra la corrosi\u00f3n, asegurando la longevidad de sus equipos.<\/p> <p> <a href=\"\/wax-pro-b-power-protection\"><i class=\"fas fa-angle-double-right\"><\/i> <strong>Wax Pro B Power Protection<\/strong><\/a> | <a href=\"\/wax-pro-b-power-protection-moto\"><i class=\"fas fa-angle-double-right\"><\/i><strong> Wax Pro B Power Protection Moto<\/strong><\/a> | <a href=\"\/wax-pro-premium\"><i class=\"fas fa-angle-double-right\"><\/i><strong> Wax Pro Premium<\/strong><\/a><\/p> | <a href=\"\/wax-pro-power-care-3-en-1\"><i class=\"fas fa-angle-double-right\"><\/i> <strong>Wax Pro Power Care 3 En 1<\/strong><\/a><\/p><\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial__image\">\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/sowax.fr\/wp-content\/uploads\/2023\/11\/Auto_Moto-scaled.jpg\" alt=\"Protecci\u00f3n de la pintura contra las agresiones exteriores\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Protecci\u00f3n de la pintura contra las agresiones exteriores<\/span><span class=\"elementor-testimonial__title\"><p>Programa completo para la preparaci\u00f3n y el mantenimiento de veh\u00edculos nuevos y usados, garantizando una protecci\u00f3n y un brillo intenso de la pintura durante al menos 3 a\u00f1os.<\/p> <p> <a href=\"\/wax-pro-b-power-protection\"><i class=\"fas fa-angle-double-right\"><\/i> <strong>Wax Pro B Power Protection<\/strong><\/a> | <a href=\"\/wax-pro-b-power-protection-moto\"><i class=\"fas fa-angle-double-right\"><\/i><strong> Wax Pro B Power Protection Moto<\/strong><\/a> | <a href=\"\/wax-pro-premium\"><i class=\"fas fa-angle-double-right\"><\/i><strong> Wax Pro Premium<\/strong><\/a> | <a href=\"\/wax-pro-power-care-3-en-1\"><i class=\"fas fa-angle-double-right\"><\/i> <strong>Wax Pro Power Care 3 En 1<\/strong><\/a><\/p><\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t\t<span class=\"elementor-screen-only\">Anterior<\/span>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t\t<span class=\"elementor-screen-only\">Siguiente<\/span>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-dc5de11 elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"dc5de11\" data-element_type=\"section\" id=\"solutions\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1ade8b0\" data-id=\"1ade8b0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-cd670c4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cd670c4\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-342646a elementor-invisible\" data-id=\"342646a\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:100}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6d0878f elementor-widget elementor-widget-image\" data-id=\"6d0878f\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"614\" src=\"https:\/\/sowax.fr\/wp-content\/uploads\/2023\/10\/Innovation-1024x614.jpeg\" class=\"attachment-large size-large wp-image-3986\" alt=\"\" srcset=\"https:\/\/sowax.fr\/wp-content\/uploads\/2023\/10\/Innovation-1024x614.jpeg 1024w, https:\/\/sowax.fr\/wp-content\/uploads\/2023\/10\/Innovation-300x180.jpeg 300w, https:\/\/sowax.fr\/wp-content\/uploads\/2023\/10\/Innovation-768x461.jpeg 768w, https:\/\/sowax.fr\/wp-content\/uploads\/2023\/10\/Innovation-1536x922.jpeg 1536w, https:\/\/sowax.fr\/wp-content\/uploads\/2023\/10\/Innovation-2048x1229.jpeg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8e52a9e elementor-view-stacked elementor-absolute icon-border-white elementor-shape-circle elementor-widget elementor-widget-icon\" data-id=\"8e52a9e\" data-element_type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-microscope\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d69ecef elementor-widget elementor-widget-heading\" data-id=\"d69ecef\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Innovaci\u00f3n<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bf0cf2b elementor-widget elementor-widget-text-editor\" data-id=\"bf0cf2b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Desde 1999, SOFDI lucha contra la corrosi\u00f3n y la alteraci\u00f3n de los metales.<\/p><p>SOFDI se especializa en el desarrollo de <strong>conceptos de alta tecnolog\u00eda para la protecci\u00f3n de la maquinaria industrial y la pintura de los autom\u00f3viles<\/strong>. Estos productos de alta calidad se mejoran <strong>constantemente a trav\u00e9s de la investigaci\u00f3n y desarrollo de nuestro departamento t\u00e9cnico<\/strong>.<\/p><p>Nuestros productos se fabrican de acuerdo con las <strong>normas t\u00e9cnicas y cient\u00edficas<\/strong> m\u00e1s rigurosas.<\/p><p>Expertos en la lucha contra la corrosi\u00f3n, hemos ampliado nuestra \u00e1rea de aplicaci\u00f3n a la protecci\u00f3n de pinturas de autom\u00f3viles expuestas a agresiones ambientales.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-9796370 elementor-invisible\" data-id=\"9796370\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:200}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b57ff53 elementor-view-stacked elementor-absolute icon-border-white elementor-shape-circle elementor-widget elementor-widget-icon\" data-id=\"b57ff53\" data-element_type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-concierge-bell\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b466f5d elementor-widget elementor-widget-image\" data-id=\"b466f5d\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"614\" src=\"https:\/\/sowax.fr\/wp-content\/uploads\/2023\/10\/Service-1024x614.jpg\" class=\"attachment-large size-large wp-image-4002\" alt=\"\" srcset=\"https:\/\/sowax.fr\/wp-content\/uploads\/2023\/10\/Service-1024x614.jpg 1024w, https:\/\/sowax.fr\/wp-content\/uploads\/2023\/10\/Service-300x180.jpg 300w, https:\/\/sowax.fr\/wp-content\/uploads\/2023\/10\/Service-768x461.jpg 768w, https:\/\/sowax.fr\/wp-content\/uploads\/2023\/10\/Service-1536x922.jpg 1536w, https:\/\/sowax.fr\/wp-content\/uploads\/2023\/10\/Service-2048x1229.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7c1701d elementor-widget elementor-widget-heading\" data-id=\"7c1701d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">servicios<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-63dc6ff elementor-widget elementor-widget-text-editor\" data-id=\"63dc6ff\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Cada tratamiento de protecci\u00f3n es aplicado por <strong>profesionales certificados y capacitados por SOFDI<\/strong>. Con m\u00e1s de 20 a\u00f1os de experiencia en el diagn\u00f3stico de las causas de la oxidaci\u00f3n, nuestros expertos est\u00e1n a su disposici\u00f3n para analizar sus necesidades.<\/p><p><strong>Industriales<\/strong>, le brindamos asesoramiento y recomendamos soluciones adaptadas a su actividad en la lucha contra la corrosi\u00f3n, un verdadero problema en la industria.<\/p><p><strong>Concesionarios<\/strong>, capacitamos a sus equipos de ventas y preparadores. Estamos presentes en todo el territorio nacional y visitamos regularmente a todos nuestros\u00a0 concesionarios asociados, ofreci\u00e9ndoles as\u00ed un apoyo personalizado.<\/p><p><strong><a href=\"https:\/\/sowax.fr\/es\/#contact\">Cont\u00e1ctenos<\/a><\/strong> para obtener <strong>una soluci\u00f3n a la medida.<\/strong><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-4bddaea elementor-invisible\" data-id=\"4bddaea\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:300}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f31499b elementor-widget elementor-widget-image\" data-id=\"f31499b\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"614\" src=\"https:\/\/sowax.fr\/wp-content\/uploads\/2023\/10\/Satifaction-client-1024x614.jpg\" class=\"attachment-large size-large wp-image-3998\" alt=\"\" srcset=\"https:\/\/sowax.fr\/wp-content\/uploads\/2023\/10\/Satifaction-client-1024x614.jpg 1024w, https:\/\/sowax.fr\/wp-content\/uploads\/2023\/10\/Satifaction-client-300x180.jpg 300w, https:\/\/sowax.fr\/wp-content\/uploads\/2023\/10\/Satifaction-client-768x461.jpg 768w, https:\/\/sowax.fr\/wp-content\/uploads\/2023\/10\/Satifaction-client-1536x922.jpg 1536w, https:\/\/sowax.fr\/wp-content\/uploads\/2023\/10\/Satifaction-client-2048x1229.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5bbab40 elementor-view-stacked elementor-absolute icon-border-white elementor-shape-circle elementor-widget elementor-widget-icon\" data-id=\"5bbab40\" data-element_type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-thumbs-up\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c84a048 elementor-widget elementor-widget-heading\" data-id=\"c84a048\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Satisfacci\u00f3n<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-66374f0 elementor-widget elementor-widget-text-editor\" data-id=\"66374f0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Los tratamientos SOFDI tienen una<strong> reputaci\u00f3n mundial<\/strong> como productos utilizados en la fabricaci\u00f3n de alto valor agregado.<\/p><p>Nuestra experiencia y competencia en la protecci\u00f3n contra la corrosi\u00f3n y la protecci\u00f3n de la pintura nos <strong>posicionan como l\u00edderes<\/strong> en el sector automovil y en el sector industrial.\u00a0<\/p><p>Hoy en d\u00eda, ofrecemos una gama completa de productos dirigidos a :<\/p><ul><li>el <strong>sector del autom\u00f3vil<\/strong><br \/><small class=\"text-muted\">(fabricantes de veh\u00edculos, concesionarios y vendedores de veh\u00edculos usados, talleres de pintura y reparaci\u00f3n&#8230;),<\/small><\/li><li>el <strong>sector industrial\u00a0 \u00a0 \u00a0 \u00a0<\/strong><small class=\"text-muted\">(transporte, almacenamiento, mantenimiento, maquinaria de construcci\u00f3n, grandes carrocer\u00edas industriales, maquinaria, herramientas, piezas, aeron\u00e1utica&#8230;).<\/small><\/li><\/ul>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fc5326e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fc5326e\" data-element_type=\"section\" id=\"benefits\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-48dd3cd\" data-id=\"48dd3cd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-05b73f8 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"05b73f8\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">NUESTROS BENEFICIOS<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ce21b83 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"ce21b83\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Ofrecemos protecci\u00f3n para todos los veh\u00edculos nuevos y usados y materiales industriales.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-7fd4696 elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"7fd4696\" data-element_type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;bounceInUp&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-178a78e\" data-id=\"178a78e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c395de4 elementor-position-left elementor-view-default elementor-mobile-position-top elementor-vertical-align-top elementor-widget elementor-widget-icon-box\" data-id=\"c395de4\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon elementor-animation-\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-sun\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tProtecci\u00f3n UV\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tConserva el color gracias a sus potentes filtros UV.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-ad426f8\" data-id=\"ad426f8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9904aa7 elementor-position-left elementor-view-default elementor-mobile-position-top elementor-vertical-align-top elementor-widget elementor-widget-icon-box\" data-id=\"9904aa7\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon elementor-animation-\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-cloud-showers-heavy\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tProtecci\u00f3n contra la intemperie\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tForma una pel\u00edcula protectora impermeable de gran adherencia.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-2c3fc1a\" data-id=\"2c3fc1a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4295fc8 elementor-position-left elementor-view-default elementor-mobile-position-top elementor-vertical-align-top elementor-widget elementor-widget-icon-box\" data-id=\"4295fc8\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon elementor-animation-\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-tint-slash\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tEfecto repelente al agua\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tMejora la seguridad de  la conducci\u00f3n bajo la lluvia.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-8010aea elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"8010aea\" data-element_type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;bounceInUp&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-a7769bd\" data-id=\"a7769bd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7db2e34 elementor-position-left elementor-view-default elementor-mobile-position-top elementor-vertical-align-top elementor-widget elementor-widget-icon-box\" data-id=\"7db2e34\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon elementor-animation-\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-snowflake\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tProtecci\u00f3n contra el aire fr\u00edo y el ambiente salino. \t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tEvita la oxidaci\u00f3n causada por la dispersi\u00f3n de sales y la niebla marina.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-e991f11\" data-id=\"e991f11\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-10a2ca6 elementor-position-left elementor-view-default elementor-mobile-position-top elementor-vertical-align-top elementor-widget elementor-widget-icon-box\" data-id=\"10a2ca6\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon elementor-animation-\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-euro-sign\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tMantiene el valor de su Veh\u00edculo\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tMantiene su veh\u00edculo como nuevo durante m\u00e1s tiempo, aumentando as\u00ed su valor de reventa.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-9dc02a9\" data-id=\"9dc02a9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5563c02 elementor-position-left elementor-view-default elementor-mobile-position-top elementor-vertical-align-top elementor-widget elementor-widget-icon-box\" data-id=\"5563c02\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon elementor-animation-\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-cogs\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tMantenimiento industrial\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tLlega f\u00e1cilmente a zonas inaccesibles y alarga la vida de carrocer\u00edas, piezas y accesorios.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-cdf9245 elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"cdf9245\" data-element_type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;bounceInUp&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-91e36d2\" data-id=\"91e36d2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b57ff0f elementor-position-left elementor-view-default elementor-mobile-position-top elementor-vertical-align-top elementor-widget elementor-widget-icon-box\" data-id=\"b57ff0f\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon elementor-animation-\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-fill-drip\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tProtecci\u00f3n contra la suciedad\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tFacilita la eliminaci\u00f3n de suciedad, insectos y otros materiales agresivos.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-add91f3\" data-id=\"add91f3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f4ca6f6 elementor-position-left elementor-view-default elementor-mobile-position-top elementor-vertical-align-top elementor-widget elementor-widget-icon-box\" data-id=\"f4ca6f6\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon elementor-animation-\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-gem\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tEfecto de alto brillo\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tMantiene durablemente el brillo intenso.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-cdd6805\" data-id=\"cdd6805\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c5f9572 elementor-position-left elementor-view-default elementor-mobile-position-top elementor-vertical-align-top elementor-widget elementor-widget-icon-box\" data-id=\"c5f9572\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon elementor-animation-\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-piggy-bank\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tAhorro diario\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tAhorra tiempo de limpieza y preserva el valor de veh\u00edculos y materiales.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bd1eeb6 elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"bd1eeb6\" data-element_type=\"section\" id=\"call-to-action\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cf62a01\" data-id=\"cf62a01\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9491dc7 elementor-widget elementor-widget-heading\" data-id=\"9491dc7\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><span>Descubra a\u00fan m\u00e1s ventajas<\/span><\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2608c21 elementor-widget elementor-widget-text-editor\" data-id=\"2608c21\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>P\u00f3ngase en contacto con nosotros para obtener m\u00e1s informaci\u00f3n sobre nuestros tratamientos exclusivos y encontrar la soluci\u00f3n adecuada.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eb28107 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"eb28107\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"\/fr\/#contact\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Contacto<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5dc858e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5dc858e\" data-element_type=\"section\" id=\"treatments\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-aac00af\" data-id=\"aac00af\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e04ebc6 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"e04ebc6\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-large\">NUESTROS TRATAMIENTOS EXCLUSIVOS<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-93c8dbe elementor-widget elementor-widget-post-filter\" data-id=\"93c8dbe\" data-element_type=\"widget\" data-widget_type=\"post-filter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n    <div>\n      <ul class=\"elementor-portfolio__filters cat-filter-for-treatment-wrap\" id=\"filter-category-93c8dbe\" data-hide-empty=\"\">\n        <li\n    class=\"super-cat-post-filter elementor-portfolio__filter elementor-active\"\n    data-term=\"\"\n    data-container=\"filter-category-93c8dbe\"\n    data-posts=\"treatment-wrap\">\n    Tous\n    <\/li>        <li\n      class=\"super-cat-post-filter elementor-portfolio__filter\"\n      data-term=\"category-anticorrosion\"\n      data-container=\"filter-category-93c8dbe\"\n      data-posts=\"treatment-wrap\">\n      Anticorrosi\u00f3n\n      <\/li><li\n      class=\"super-cat-post-filter elementor-portfolio__filter\"\n      data-term=\"category-exterior\"\n      data-container=\"filter-category-93c8dbe\"\n      data-posts=\"treatment-wrap\">\n      Exterior\n      <\/li><li\n      class=\"super-cat-post-filter elementor-portfolio__filter\"\n      data-term=\"category-interior\"\n      data-container=\"filter-category-93c8dbe\"\n      data-posts=\"treatment-wrap\">\n      Interior\n      <\/li><li\n      class=\"super-cat-post-filter elementor-portfolio__filter\"\n      data-term=\"category-mantenimiento\"\n      data-container=\"filter-category-93c8dbe\"\n      data-posts=\"treatment-wrap\">\n      Mantenimiento\n      <\/li><li\n      class=\"super-cat-post-filter elementor-portfolio__filter\"\n      data-term=\"category-mantenimiento-interior-exterior\"\n      data-container=\"filter-category-93c8dbe\"\n      data-posts=\"treatment-wrap\">\n      Mantenimiento interior\/exterior\n      <\/li><li\n      class=\"super-cat-post-filter elementor-portfolio__filter\"\n      data-term=\"category-sellado-de-pintura\"\n      data-container=\"filter-category-93c8dbe\"\n      data-posts=\"treatment-wrap\">\n      Sellado de pintura\n      <\/li><li\n      class=\"super-cat-post-filter elementor-portfolio__filter\"\n      data-term=\"category-transporte-almacenamiento\"\n      data-container=\"filter-category-93c8dbe\"\n      data-posts=\"treatment-wrap\">\n      Transporte &amp; almacenamiento\n      <\/li>      <\/ul>\n    <\/div>\n\n    \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9b03778 elementor-grid-3 elementor-grid-tablet-2 elementor-grid-mobile-1 elementor-posts--thumbnail-top elementor-widget elementor-widget-posts\" data-id=\"9b03778\" data-element_type=\"widget\" id=\"treatment-wrap\" data-settings=\"{&quot;classic_columns&quot;:&quot;3&quot;,&quot;classic_columns_tablet&quot;:&quot;2&quot;,&quot;classic_columns_mobile&quot;:&quot;1&quot;,&quot;classic_row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:35,&quot;sizes&quot;:[]},&quot;classic_row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;classic_row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"posts.classic\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-posts-container elementor-posts elementor-posts--skin-classic elementor-grid\">\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-4459 treatment type-treatment status-publish has-post-thumbnail hentry category-exterieur category-exterior category-sellado-de-pintura\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/sowax.fr\/es\/treatment\/wax-pro-b-power-protection\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"150\" src=\"https:\/\/sowax.fr\/wp-content\/uploads\/2024\/03\/Voiture_Noir-300x150.jpeg\" class=\"attachment-medium size-medium wp-image-13039\" alt=\"\" srcset=\"https:\/\/sowax.fr\/wp-content\/uploads\/2024\/03\/Voiture_Noir-300x150.jpeg 300w, https:\/\/sowax.fr\/wp-content\/uploads\/2024\/03\/Voiture_Noir-1024x512.jpeg 1024w, https:\/\/sowax.fr\/wp-content\/uploads\/2024\/03\/Voiture_Noir-768x384.jpeg 768w, https:\/\/sowax.fr\/wp-content\/uploads\/2024\/03\/Voiture_Noir-1536x768.jpeg 1536w, https:\/\/sowax.fr\/wp-content\/uploads\/2024\/03\/Voiture_Noir-2048x1024.jpeg 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/sowax.fr\/es\/treatment\/wax-pro-b-power-protection\/\" >\n\t\t\t\tWax Pro B Power Protection\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Protecci\u00f3n de la pintura<\/p>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-1326 treatment type-treatment status-publish has-post-thumbnail hentry category-exterieur category-scellement-de-peinture\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/sowax.fr\/es\/treatment\/wax-pro-premium\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/sowax.fr\/wp-content\/uploads\/2024\/03\/Voiture_rouge_neutre-300x200.jpeg\" class=\"attachment-medium size-medium wp-image-12960\" alt=\"\" srcset=\"https:\/\/sowax.fr\/wp-content\/uploads\/2024\/03\/Voiture_rouge_neutre-300x200.jpeg 300w, https:\/\/sowax.fr\/wp-content\/uploads\/2024\/03\/Voiture_rouge_neutre-1024x683.jpeg 1024w, https:\/\/sowax.fr\/wp-content\/uploads\/2024\/03\/Voiture_rouge_neutre-768x512.jpeg 768w, https:\/\/sowax.fr\/wp-content\/uploads\/2024\/03\/Voiture_rouge_neutre-1536x1025.jpeg 1536w, https:\/\/sowax.fr\/wp-content\/uploads\/2024\/03\/Voiture_rouge_neutre-2048x1367.jpeg 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/sowax.fr\/es\/treatment\/wax-pro-premium\/\" >\n\t\t\t\tWax Pro Premium\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Limpieza, protecci\u00f3n y mantenimiento completo para su autom\u00f3vil, tanto en el interior como en el exterior<\/p>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-1320 treatment type-treatment status-publish has-post-thumbnail hentry category-exterieur category-exterior category-sellado-de-pintura\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/sowax.fr\/es\/treatment\/wax-pro-b-power-protection-moto\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"159\" src=\"https:\/\/sowax.fr\/wp-content\/uploads\/2022\/05\/Moto_bleu-300x159.jpg\" class=\"attachment-medium size-medium wp-image-10141\" alt=\"\" srcset=\"https:\/\/sowax.fr\/wp-content\/uploads\/2022\/05\/Moto_bleu-300x159.jpg 300w, https:\/\/sowax.fr\/wp-content\/uploads\/2022\/05\/Moto_bleu-1024x543.jpg 1024w, https:\/\/sowax.fr\/wp-content\/uploads\/2022\/05\/Moto_bleu-768x408.jpg 768w, https:\/\/sowax.fr\/wp-content\/uploads\/2022\/05\/Moto_bleu-1536x815.jpg 1536w, https:\/\/sowax.fr\/wp-content\/uploads\/2022\/05\/Moto_bleu-2048x1087.jpg 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/sowax.fr\/es\/treatment\/wax-pro-b-power-protection-moto\/\" >\n\t\t\t\tWax Pro B Power Protection Moto\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Protecci\u00f3n de la pintura<\/p>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-1311 treatment type-treatment status-publish has-post-thumbnail hentry category-exterior category-interior category-mantenimiento-interior-exterior\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/sowax.fr\/es\/treatment\/wax-pro-power-care-3-en-1\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/sowax.fr\/wp-content\/uploads\/2022\/05\/Suv_sombre-300x200.jpg\" class=\"attachment-medium size-medium wp-image-10045\" alt=\"\" srcset=\"https:\/\/sowax.fr\/wp-content\/uploads\/2022\/05\/Suv_sombre-300x200.jpg 300w, https:\/\/sowax.fr\/wp-content\/uploads\/2022\/05\/Suv_sombre-1024x683.jpg 1024w, https:\/\/sowax.fr\/wp-content\/uploads\/2022\/05\/Suv_sombre-768x512.jpg 768w, https:\/\/sowax.fr\/wp-content\/uploads\/2022\/05\/Suv_sombre-1536x1024.jpg 1536w, https:\/\/sowax.fr\/wp-content\/uploads\/2022\/05\/Suv_sombre-2048x1365.jpg 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/sowax.fr\/es\/treatment\/wax-pro-power-care-3-en-1\/\" >\n\t\t\t\tWax Pro Power Care 3 En 1\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Tratamiento<\/p>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-1317 treatment type-treatment status-publish has-post-thumbnail hentry category-anti-corrosion-pt-pt category-anticorrosion category-maintenance-pt-pt category-mantenimiento\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/sowax.fr\/es\/treatment\/wax-pro-2001-la\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"100\" src=\"https:\/\/sowax.fr\/wp-content\/uploads\/2022\/04\/Camion_Plan_cote_bleu-2-300x100.jpeg\" class=\"attachment-medium size-medium wp-image-3970\" alt=\"\" srcset=\"https:\/\/sowax.fr\/wp-content\/uploads\/2022\/04\/Camion_Plan_cote_bleu-2-300x100.jpeg 300w, https:\/\/sowax.fr\/wp-content\/uploads\/2022\/04\/Camion_Plan_cote_bleu-2-1024x341.jpeg 1024w, https:\/\/sowax.fr\/wp-content\/uploads\/2022\/04\/Camion_Plan_cote_bleu-2-768x256.jpeg 768w, https:\/\/sowax.fr\/wp-content\/uploads\/2022\/04\/Camion_Plan_cote_bleu-2-1536x511.jpeg 1536w, https:\/\/sowax.fr\/wp-content\/uploads\/2022\/04\/Camion_Plan_cote_bleu-2-2048x682.jpeg 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/sowax.fr\/es\/treatment\/wax-pro-2001-la\/\" >\n\t\t\t\tWax Pro 2001 LA\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Prevenci\u00f3n de la corrosi\u00f3n en cavidades<\/p>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-1299 treatment type-treatment status-publish has-post-thumbnail hentry category-transport-stockage category-transporte-almacenamiento\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/sowax.fr\/es\/treatment\/storoil-motorstore-vci-10\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"199\" src=\"https:\/\/sowax.fr\/wp-content\/uploads\/2022\/04\/Grands_reservoirs-3-300x199.jpg\" class=\"attachment-medium size-medium wp-image-4410\" alt=\"\" srcset=\"https:\/\/sowax.fr\/wp-content\/uploads\/2022\/04\/Grands_reservoirs-3-300x199.jpg 300w, https:\/\/sowax.fr\/wp-content\/uploads\/2022\/04\/Grands_reservoirs-3-1024x681.jpg 1024w, https:\/\/sowax.fr\/wp-content\/uploads\/2022\/04\/Grands_reservoirs-3-768x511.jpg 768w, https:\/\/sowax.fr\/wp-content\/uploads\/2022\/04\/Grands_reservoirs-3-1536x1021.jpg 1536w, https:\/\/sowax.fr\/wp-content\/uploads\/2022\/04\/Grands_reservoirs-3-2048x1362.jpg 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/sowax.fr\/es\/treatment\/storoil-motorstore-vci-10\/\" >\n\t\t\t\tStoroil Motorstore VCI 10\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Protecci\u00f3n de larga duraci\u00f3n contra la corrosi\u00f3n en el interior de los tanques.<\/p>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bed6b47 elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"bed6b47\" data-element_type=\"section\" id=\"numbers\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-859c586\" data-id=\"859c586\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fd1de42 elementor-widget elementor-widget-heading\" data-id=\"fd1de42\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-large\">WAX PRO EN CIFRAS<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7e47e0b elementor-widget elementor-widget-text-editor\" data-id=\"7e47e0b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Los hechos suelen ser mejores que la ret\u00f3rica<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6ecab3b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6ecab3b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-0da6c95\" data-id=\"0da6c95\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4bd5a81 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"4bd5a81\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-store\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cd8abd8 elementor-widget elementor-widget-counter\" data-id=\"cd8abd8\" data-element_type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">M\u00e1s de 3.000 concesionarios de todas las marcas son fieles a SOFDI en Europa.<\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"3000\" data-from-value=\"0\">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\"><\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-8bd5619\" data-id=\"8bd5619\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4769a46 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"4769a46\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-birthday-cake\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6a5eb89 elementor-widget elementor-widget-counter\" data-id=\"6a5eb89\" data-element_type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">SOFDI es l\u00edder en protecci\u00f3n contra la corrosi\u00f3n desde hace m\u00e1s de 20 a\u00f1os.<\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"1999\" data-from-value=\"0\">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\"><\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-91d5063\" data-id=\"91d5063\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c2a3894 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"c2a3894\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-industry\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-862e8c0 elementor-widget elementor-widget-counter\" data-id=\"862e8c0\" data-element_type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">Ese es el n\u00famero de grandes grupos a los que apoyamos, y crece d\u00eda a d\u00eda.<\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"60\" data-from-value=\"0\">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\"><\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-6e1eaa0\" data-id=\"6e1eaa0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-32bbc13 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"32bbc13\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-tachometer-alt\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c482d6b elementor-widget elementor-widget-counter\" data-id=\"c482d6b\" data-element_type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">2.000.000 de veh\u00edculos gestionados por la red de concesionarios SOFDI<\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"2\" data-from-value=\"0\">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\">M<\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8fc178f elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"8fc178f\" data-element_type=\"section\" id=\"uses\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9165f2c\" data-id=\"9165f2c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4fc1205 elementor-widget elementor-widget-heading\" data-id=\"4fc1205\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">ALGUNOS USOS<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-260abff elementor-widget elementor-widget-text-editor\" data-id=\"260abff\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Los tratamientos WAX PRO se adaptan a tus necesidades<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9f599e4 elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"9f599e4\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;6&quot;,&quot;slides_to_scroll&quot;:&quot;6&quot;,&quot;navigation&quot;:&quot;dots&quot;,&quot;lazyload&quot;:&quot;yes&quot;,&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:30,&quot;sizes&quot;:[]},&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500,&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 of 15\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/sowax.fr\/wp-content\/uploads\/2023\/10\/Yacht-300x200.jpeg\" alt=\"Yate\" \/><div class=\"swiper-lazy-preloader\"><\/div><figcaption class=\"elementor-image-carousel-caption\">Yate<\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 of 15\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/sowax.fr\/wp-content\/uploads\/2023\/10\/Bus-300x200.jpg\" alt=\"Autocar \/ Autob\u00fas\" \/><div class=\"swiper-lazy-preloader\"><\/div><figcaption class=\"elementor-image-carousel-caption\">Autocar \/ Autob\u00fas <\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 of 15\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/sowax.fr\/wp-content\/uploads\/2023\/10\/Closeup-300x200.jpg\" alt=\"coche\" \/><div class=\"swiper-lazy-preloader\"><\/div><figcaption class=\"elementor-image-carousel-caption\">coche<\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 of 15\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/sowax.fr\/wp-content\/uploads\/2023\/10\/Bulldozer-300x200.jpg\" alt=\"Ingenier\u00eda civil \/ Maquinaria de obra\" \/><div class=\"swiper-lazy-preloader\"><\/div><figcaption class=\"elementor-image-carousel-caption\">Ingenier\u00eda civil \/ Maquinaria de obra<\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 of 15\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/sowax.fr\/wp-content\/uploads\/2023\/10\/Zone-industriel-300x200.jpg\" alt=\"F\u00e1brica \/ Hangar \/ Almac\u00e9n\" \/><div class=\"swiper-lazy-preloader\"><\/div><figcaption class=\"elementor-image-carousel-caption\">F\u00e1brica \/ Hangar \/ Almac\u00e9n<\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 of 15\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/sowax.fr\/wp-content\/uploads\/2023\/10\/Avion-300x200.jpg\" alt=\"Avi\u00f3n \/ Jet\" \/><div class=\"swiper-lazy-preloader\"><\/div><figcaption class=\"elementor-image-carousel-caption\">Avi\u00f3n \/ Jet<\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 of 15\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/sowax.fr\/wp-content\/uploads\/2023\/10\/Camion-1-300x200.jpg\" alt=\"Veh\u00edculos pesados \/ Camiones \/ Semirremolques\" \/><div class=\"swiper-lazy-preloader\"><\/div><figcaption class=\"elementor-image-carousel-caption\">Veh\u00edculos pesados \/ Camiones \/ Semirremolques<\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 of 15\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/sowax.fr\/wp-content\/uploads\/2023\/10\/Machine-industrielle-300x200.jpg\" alt=\"Piezas \/ Herramientas \/ Mantenimiento\" \/><div class=\"swiper-lazy-preloader\"><\/div><figcaption class=\"elementor-image-carousel-caption\">Piezas \/ Herramientas \/ Mantenimiento<\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 of 15\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/sowax.fr\/wp-content\/uploads\/2023\/10\/Train-300x200.jpg\" alt=\"Red ferroviaria \/ Tren \/ Tranv\u00eda \/ Metro\" \/><div class=\"swiper-lazy-preloader\"><\/div><figcaption class=\"elementor-image-carousel-caption\">Red ferroviaria \/ Tren \/ Tranv\u00eda \/ Metro<\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"10 of 15\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/sowax.fr\/wp-content\/uploads\/2023\/10\/Caterpillars_parking-300x200.jpeg\" alt=\"Transporte \/ Almacenamiento construction work vehicles, parking\" \/><div class=\"swiper-lazy-preloader\"><\/div><figcaption class=\"elementor-image-carousel-caption\">Transporte \/ Almacenamiento construction work vehicles, parking<\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"11 of 15\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/sowax.fr\/wp-content\/uploads\/2023\/10\/Camionnette-300x200.jpg\" alt=\"Furgoneta \/ Monovolumen \/ Furg\u00f3n de carga\" \/><div class=\"swiper-lazy-preloader\"><\/div><figcaption class=\"elementor-image-carousel-caption\">Furgoneta \/ Monovolumen \/ Furg\u00f3n de carga<\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"12 of 15\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/sowax.fr\/wp-content\/uploads\/2023\/10\/Eolienne-300x200.jpeg\" alt=\"aerogenerador\" \/><div class=\"swiper-lazy-preloader\"><\/div><figcaption class=\"elementor-image-carousel-caption\">aerogenerador<\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"13 of 15\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/sowax.fr\/wp-content\/uploads\/2023\/10\/Satellite-300x200.jpg\" alt=\"Sat\u00e9lite\" \/><div class=\"swiper-lazy-preloader\"><\/div><figcaption class=\"elementor-image-carousel-caption\">Sat\u00e9lite<\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"14 of 15\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/sowax.fr\/wp-content\/uploads\/2023\/10\/Plate-forme-petroliere-300x200.jpg\" alt=\"Plataforma petrol\u00edfera\" \/><div class=\"swiper-lazy-preloader\"><\/div><figcaption class=\"elementor-image-carousel-caption\">Plataforma petrol\u00edfera<\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"15 of 15\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/sowax.fr\/wp-content\/uploads\/2023\/10\/Grands_reservoirs-300x200.jpg\" alt=\"Grandes embalses\" \/><div class=\"swiper-lazy-preloader\"><\/div><figcaption class=\"elementor-image-carousel-caption\">Grandes embalses<\/figcaption><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9cfff43 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9cfff43\" data-element_type=\"section\" id=\"warranties\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b837e2c\" data-id=\"b837e2c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-502cecb elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"502cecb\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">GARANT\u00cdAS DEL PROVEEDOR<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-957095c elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"957095c\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Garantizamos el tratamiento &#8230;<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-eb26017 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"eb26017\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-845b3c1 elementor-invisible\" data-id=\"845b3c1\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;bounceInLeft&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-72a9ef9 elementor-position-left elementor-view-default elementor-mobile-position-top elementor-vertical-align-top elementor-widget elementor-widget-icon-box\" data-id=\"72a9ef9\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon elementor-animation-\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-award\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tControl de garant\u00eda del cliente final\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-256ca2c elementor-widget elementor-widget-text-editor\" data-id=\"256ca2c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Compruebe la garant\u00eda de WAX PRO Paint Seal.<\/p><p>Para comprobar el estado de su garant\u00eda WAX PRO Gard en cualquier momento.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e51a208 elementor-widget elementor-widget-button\" data-id=\"e51a208\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6MTMzODksInRvZ2dsZSI6ZmFsc2V9\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Comprobar mi garant\u00eda<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-d5aefe0 elementor-invisible\" data-id=\"d5aefe0\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;bounceInRight&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5d76ae7 elementor-position-left elementor-view-default elementor-mobile-position-top elementor-vertical-align-top elementor-widget elementor-widget-icon-box\" data-id=\"5d76ae7\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon elementor-animation-\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-certificate\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tRegistro de garant\u00edas por los distribuidores\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-be2a71a elementor-widget elementor-widget-text-editor\" data-id=\"be2a71a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Para registrar las garant\u00edas de los clientes, por favor haga clic en el bot\u00f3n de abajo.<\/p><p>Utilice esta opci\u00f3n para registrar WAX PRO Gard en cualquier momento.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0f3382d elementor-widget elementor-widget-button\" data-id=\"0f3382d\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/extranet.sowax.fr\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Acceda a su cuenta<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-58203e0 elementor-widget elementor-widget-heading\" data-id=\"58203e0\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">M\u00c1S QUE UNA GARANT\u00cdA, UNA \u00c9TICA<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a16fb08 elementor-widget elementor-widget-text-editor\" data-id=\"a16fb08\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Prestamos rigurosa atenci\u00f3n a nuestra carta de calidad.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-460a7c2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"460a7c2\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-73e64fb elementor-invisible\" data-id=\"73e64fb\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;bounceInLeft&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c505697 elementor-position-left elementor-view-default elementor-mobile-position-top elementor-vertical-align-top elementor-widget elementor-widget-icon-box\" data-id=\"c505697\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon elementor-animation-\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-graduation-cap\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tFormaci\u00f3n para distribuidores autorizados\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-77de312 elementor-widget elementor-widget-text-editor\" data-id=\"77de312\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Certificamos que el personal especializado en preparaci\u00f3n de veh\u00edculos de su concesionario ha recibido formaci\u00f3n en la aplicaci\u00f3n de los conceptos WAX PRO.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-d0bdf07 elementor-invisible\" data-id=\"d0bdf07\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;bounceInRight&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-231fe35 elementor-position-left elementor-view-default elementor-mobile-position-top elementor-vertical-align-top elementor-widget elementor-widget-icon-box\" data-id=\"231fe35\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon elementor-animation-\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-leaf\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tGarant\u00eda medioambiental\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8f6bf72 elementor-widget elementor-widget-text-editor\" data-id=\"8f6bf72\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Los productos WAX PRO son respetuosos con el medio ambiente y no contienen silicona.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-db23fd0 elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"db23fd0\" data-element_type=\"section\" id=\"contact\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-97d8110\" data-id=\"97d8110\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c9861f0 elementor-widget elementor-widget-heading\" data-id=\"c9861f0\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">CONTACTO<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-50f74fe elementor-widget elementor-widget-text-editor\" data-id=\"50f74fe\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>P\u00f3ngase en contacto con nosotros para obtener m\u00e1s informaci\u00f3n sobre las soluciones de tratamiento WAX PRO<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3674e1b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3674e1b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-409006c\" data-id=\"409006c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a81fe50 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"a81fe50\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-address-book\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-efd8056 elementor-widget elementor-widget-heading\" data-id=\"efd8056\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Direcci\u00f3n<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8d37b6e elementor-widget elementor-widget-text-editor\" data-id=\"8d37b6e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>27, Rue Foucher Lepelletier<br \/>92130 Issy-les-Moulineaux<br \/>France<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-ee060bf\" data-id=\"ee060bf\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c3abb3b elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"c3abb3b\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-phone\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d20a26b elementor-widget elementor-widget-heading\" data-id=\"d20a26b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Tel\u00e9fono<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ec2c9c4 elementor-widget elementor-widget-text-editor\" data-id=\"ec2c9c4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><a href=\"tel:+33146620971\">+33 (0)1 46 62 09 71<\/a><\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-6df82c8 eael-contact-form-7-button-custom elementor-widget elementor-widget-eael-contact-form-7\" data-id=\"6df82c8\" data-element_type=\"widget\" data-widget_type=\"eael-contact-form-7.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"eael-contact-form-7-wrapper\">\n                <div class=\"eael-contact-form eael-contact-form-7 eael-contact-form-6df82c8 labels-hide placeholder-show eael-contact-form-align-default\">\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f1447-o1\" lang=\"es-ES\" dir=\"ltr\" data-wpcf7-id=\"1447\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/es\/wp-json\/wp\/v2\/pages\/960#wpcf7-f1447-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Formulario de contacto\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"1447\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.5\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"es_ES\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f1447-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<div class=\"elementor-form-fields-wrapper\">\n\t<div class=\"elementor-column elementor-col-50\">\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" minlength=\"4\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Nombre y Empresa\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"elementor-column elementor-col-50\">\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Correo Electr\u00f3nico\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"elementor-column elementor-col-100\">\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-subject\"><input size=\"40\" maxlength=\"400\" minlength=\"8\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Asunto\" value=\"\" type=\"text\" name=\"your-subject\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"elementor-column elementor-col-100\">\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" minlength=\"4\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" placeholder=\"Tu mensaje\" name=\"your-message\"><\/textarea><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"elementor-column elementor-col-100\">\n\t\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Enviar tu mensaje\" \/>\n\t\t<\/p>\n\t<\/div>\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n<\/div>\n            <\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Especialista en la protecci\u00f3nde los veh\u00edculos y maquinaria industrialcontra la corrosi\u00f3n. Fabricantes y concesionarios de autom\u00f3viles y de la industrial en general, \u00a1WAX PRO est\u00e1 hecho para ti! Comience su visitaExclusivamente de profesionalespara profesionales Fabricantes y concesionarios de autom\u00f3viles y de la industrial en general, \u00a1WAX PRO est\u00e1 hecho para ti!Comience su visitaWax Pro B [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-960","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Accueil | Groupe SOFDI<\/title>\n<meta name=\"description\" content=\"WAX PRO est le premier fabricant Fran\u00e7ais sp\u00e9cialis\u00e9 dans la protection des peintures, l&#039;oxydation et l&#039;anti-corrosion.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sowax.fr\/es\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Accueil | Groupe SOFDI\" \/>\n<meta property=\"og:description\" content=\"WAX PRO est le premier fabricant Fran\u00e7ais sp\u00e9cialis\u00e9 dans la protection des peintures, l&#039;oxydation et l&#039;anti-corrosion.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sowax.fr\/es\/\" \/>\n<meta property=\"og:site_name\" content=\"Groupe SOFDI\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-30T04:17:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sowax.fr\/wp-content\/uploads\/2023\/11\/auto-moto-1.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"18 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sowax.fr\\\/es\\\/\",\"url\":\"https:\\\/\\\/sowax.fr\\\/es\\\/\",\"name\":\"Accueil | Groupe SOFDI\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sowax.fr\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sowax.fr\\\/es\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sowax.fr\\\/es\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sowax.fr\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/auto-moto-1.png\",\"datePublished\":\"2022-04-11T08:05:51+00:00\",\"dateModified\":\"2024-08-30T04:17:07+00:00\",\"description\":\"WAX PRO est le premier fabricant Fran\u00e7ais sp\u00e9cialis\u00e9 dans la protection des peintures, l'oxydation et l'anti-corrosion.\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sowax.fr\\\/es\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/sowax.fr\\\/es\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sowax.fr\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/auto-moto-1.png\",\"contentUrl\":\"https:\\\/\\\/sowax.fr\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/auto-moto-1.png\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sowax.fr\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/sowax.fr\\\/es\\\/\",\"name\":\"Groupe SOFDI\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/sowax.fr\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sowax.fr\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sowax.fr\\\/es\\\/#organization\",\"name\":\"Groupe SOFDI\",\"url\":\"https:\\\/\\\/sowax.fr\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/sowax.fr\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/sowax.fr\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-cropped-Sowax-Rouge.png\",\"contentUrl\":\"https:\\\/\\\/sowax.fr\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-cropped-Sowax-Rouge.png\",\"width\":2742,\"height\":904,\"caption\":\"Groupe SOFDI\"},\"image\":{\"@id\":\"https:\\\/\\\/sowax.fr\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Accueil | Groupe SOFDI","description":"WAX PRO est le premier fabricant Fran\u00e7ais sp\u00e9cialis\u00e9 dans la protection des peintures, l'oxydation et l'anti-corrosion.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sowax.fr\/es\/","og_locale":"es_ES","og_type":"article","og_title":"Accueil | Groupe SOFDI","og_description":"WAX PRO est le premier fabricant Fran\u00e7ais sp\u00e9cialis\u00e9 dans la protection des peintures, l'oxydation et l'anti-corrosion.","og_url":"https:\/\/sowax.fr\/es\/","og_site_name":"Groupe SOFDI","article_modified_time":"2024-08-30T04:17:07+00:00","og_image":[{"url":"https:\/\/sowax.fr\/wp-content\/uploads\/2023\/11\/auto-moto-1.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"18 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/sowax.fr\/es\/","url":"https:\/\/sowax.fr\/es\/","name":"Accueil | Groupe SOFDI","isPartOf":{"@id":"https:\/\/sowax.fr\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sowax.fr\/es\/#primaryimage"},"image":{"@id":"https:\/\/sowax.fr\/es\/#primaryimage"},"thumbnailUrl":"https:\/\/sowax.fr\/wp-content\/uploads\/2023\/11\/auto-moto-1.png","datePublished":"2022-04-11T08:05:51+00:00","dateModified":"2024-08-30T04:17:07+00:00","description":"WAX PRO est le premier fabricant Fran\u00e7ais sp\u00e9cialis\u00e9 dans la protection des peintures, l'oxydation et l'anti-corrosion.","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sowax.fr\/es\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sowax.fr\/es\/#primaryimage","url":"https:\/\/sowax.fr\/wp-content\/uploads\/2023\/11\/auto-moto-1.png","contentUrl":"https:\/\/sowax.fr\/wp-content\/uploads\/2023\/11\/auto-moto-1.png"},{"@type":"WebSite","@id":"https:\/\/sowax.fr\/es\/#website","url":"https:\/\/sowax.fr\/es\/","name":"Groupe SOFDI","description":"","publisher":{"@id":"https:\/\/sowax.fr\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sowax.fr\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/sowax.fr\/es\/#organization","name":"Groupe SOFDI","url":"https:\/\/sowax.fr\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sowax.fr\/es\/#\/schema\/logo\/image\/","url":"https:\/\/sowax.fr\/wp-content\/uploads\/2024\/02\/cropped-cropped-Sowax-Rouge.png","contentUrl":"https:\/\/sowax.fr\/wp-content\/uploads\/2024\/02\/cropped-cropped-Sowax-Rouge.png","width":2742,"height":904,"caption":"Groupe SOFDI"},"image":{"@id":"https:\/\/sowax.fr\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/sowax.fr\/es\/wp-json\/wp\/v2\/pages\/960","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sowax.fr\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/sowax.fr\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/sowax.fr\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sowax.fr\/es\/wp-json\/wp\/v2\/comments?post=960"}],"version-history":[{"count":465,"href":"https:\/\/sowax.fr\/es\/wp-json\/wp\/v2\/pages\/960\/revisions"}],"predecessor-version":[{"id":13404,"href":"https:\/\/sowax.fr\/es\/wp-json\/wp\/v2\/pages\/960\/revisions\/13404"}],"wp:attachment":[{"href":"https:\/\/sowax.fr\/es\/wp-json\/wp\/v2\/media?parent=960"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}