{"id":906,"date":"2022-04-11T08:05:51","date_gmt":"2022-04-11T08:05:51","guid":{"rendered":"https:\/\/sowax.fr\/home\/"},"modified":"2024-08-30T04:21:14","modified_gmt":"2024-08-30T04:21:14","slug":"home","status":"publish","type":"page","link":"https:\/\/sowax.fr\/fr\/","title":{"rendered":"Accueil"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"906\" class=\"elementor elementor-906 elementor-10\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-51587da elementor-section-full_width elementor-section-height-full elementor-section-height-default elementor-section-items-middle elementor-invisible\" data-id=\"51587da\" data-element_type=\"section\" id=\"intro\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b59e56b\" data-id=\"b59e56b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-8a8e67c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8a8e67c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-d96585f\" data-id=\"d96585f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e79345f header-slider elementor-hidden-tablet elementor-hidden-mobile elementor--h-position-center elementor--v-position-middle elementor-arrows-position-inside elementor-pagination-position-inside elementor-widget elementor-widget-slides\" data-id=\"e79345f\" data-element_type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;transition&quot;:&quot;slide&quot;,&quot;transition_speed&quot;:500}\" data-widget_type=\"slides.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t<div class=\"elementor-slides-wrapper elementor-main-swiper swiper\" dir=\"ltr\" data-animation=\"fadeInUp\">\n\t\t\t\t<div class=\"swiper-wrapper elementor-slides\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-repeater-item-963d42f swiper-slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-heading\"><span style=\"text-shadow: 2px 2px 5px #000;\">Exclusivement pour des professionnels<br>par des professionnels<\/span><\/div><div class=\"elementor-slide-description\"><h5 style=\"font-family: Montserrat, sans-serif; font-weight: 200;\">Constructeurs automobiles, concessionnaires automobiles ou<br \/> dans l'industrie en g\u00e9n\u00e9ral, SOWAX est fait pour vous !<\/h5>\n<\/div><a href=\"#featured-services\" class=\"elementor-button elementor-slide-button elementor-size-sm\">Commencez votre visite<\/a><\/div><\/div><\/div><div class=\"elementor-repeater-item-cc28d93 swiper-slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-heading\"><span style=\"text-shadow: 2px 2px 5px #000;\">Scellement de peinture<br>haute brillance<\/span><\/div><div class=\"elementor-slide-description\"><h5 style=\"font-family: Montserrat, sans-serif; font-weight: 200;\">Nos traitements conf\u00e8rent \u00e0 la couche de peinture des voitures, <br \/>un bouclier \u00e0 haute brillance pratiquement inviolable<\/h5><\/div><a href=\"#treatments\" class=\"elementor-button elementor-slide-button elementor-size-sm\">D\u00e9couvrez nos traitements<\/a><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t\t<span class=\"elementor-screen-only\">Diapositive pr\u00e9c\u00e9dente<\/span>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t\t<span class=\"elementor-screen-only\">Diapositive suivante<\/span>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-048ffcb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"048ffcb\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ffb4177\" data-id=\"ffb4177\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9f26dba header-slider slider-mobile elementor-hidden-desktop elementor--h-position-center elementor--v-position-middle elementor-arrows-position-inside elementor-pagination-position-inside elementor-widget elementor-widget-slides\" data-id=\"9f26dba\" data-element_type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;transition&quot;:&quot;slide&quot;,&quot;transition_speed&quot;:500}\" data-widget_type=\"slides.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t<div class=\"elementor-slides-wrapper elementor-main-swiper swiper\" dir=\"ltr\" data-animation=\"fadeInUp\">\n\t\t\t\t<div class=\"swiper-wrapper elementor-slides\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-repeater-item-6aac38f swiper-slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-heading\"><h1 style=\"text-shadow: 2px 2px 4px #000;\">Sp\u00e9cialis\u00e9e dans <br>la protection de <br>  vos v\u00e9hicules <br> et machines<br> industrielles<br> contre la <br>corrosion<\/h1><\/div><div class=\"elementor-slide-description\"><h5 style=\"font-family: Montserrat, sans-serif; font-weight: 200;\">Constructeurs automobiles,<br> concessionnaires automobiles ou<br \/> dans l'industrie en g\u00e9n\u00e9ral, <br>WAX PRO est fait pour vous !<\/h5>\n<\/div><a href=\"#featured-services\" class=\"elementor-button elementor-slide-button elementor-size-sm\"> Commencez votre visite<\/a><\/div><\/div><\/div><div class=\"elementor-repeater-item-963d42f swiper-slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-heading\"><span style=\"text-shadow: 2px 2px 5px #000;\">Exclusivement <br> pour des <br>professionnels<br>par des <br>professionnels<\/span><\/div><div class=\"elementor-slide-description\"><h5 style=\"font-family: Montserrat, sans-serif; font-weight: 200;\">Constructeurs automobiles, <br>concessionnaires automobiles ou<br \/> dans l'industrie en g\u00e9n\u00e9ral, <br>WAX PRO est fait pour vous !<\/h5>\n<\/div><a href=\"#featured-services\" class=\"elementor-button elementor-slide-button elementor-size-sm\">Commencez votre visite<\/a><\/div><\/div><\/div><div class=\"elementor-repeater-item-d8224b3 swiper-slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-heading\"><span style=\"text-shadow: 2px 2px 5px #000;\">Wax Pro B Power <br> Protection<\/span><\/div><div class=\"elementor-slide-description\"><h5 style=\"font-family: Montserrat, sans-serif; font-weight: 200;\">Le concept B Power  permet<br>\nune haute protection ultra efficace <br>de la peinture de votre\nvoiture <br>en cr\u00e9ant un bouclier de haute brillance.<\/h5><\/div><a href=\"#treatments\" class=\"elementor-button elementor-slide-button elementor-size-sm\">D\u00e9couvrez nos traitements<\/a><\/div><\/div><\/div><div class=\"elementor-repeater-item-2179f49 swiper-slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-heading\"><span style=\"text-shadow: 2px 2px 5px #000;\">Wax Pro B Power <br>Protection Moto<\/span><\/div><div class=\"elementor-slide-description\"><h5 style=\"font-family: Montserrat, sans-serif; font-weight: 200;\">Notre concept Wax Pro B Power <br>Protection Moto permet une protection <br> ultra efficace de la peinture de votre\nmoto <br> en cr\u00e9ant un bouclier de haute brillance.<\/h5><\/div><a href=\"#treatments\" class=\"elementor-button elementor-slide-button elementor-size-sm\">D\u00e9couvrez nos traitements<\/a><\/div><\/div><\/div><div class=\"elementor-repeater-item-cc28d93 swiper-slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-heading\"><span style=\"text-shadow: 2px 2px 5px #000;\">Scellement<br> de peinture<br>haute brillance<\/span><\/div><div class=\"elementor-slide-description\"><h5 style=\"font-family: Montserrat, sans-serif; font-weight: 200;\">Nos traitements conf\u00e8rent \u00e0 la couche <br>de peinture des voitures, <br \/>un bouclier \u00e0 haute brillance <br>pratiquement inviolable<\/h5><\/div><a href=\"#treatments\" class=\"elementor-button elementor-slide-button elementor-size-sm\">D\u00e9couvrez nos traitements<\/a><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t\t<span class=\"elementor-screen-only\">Diapositive pr\u00e9c\u00e9dente<\/span>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t\t<span class=\"elementor-screen-only\">Diapositive suivante<\/span>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-94ec73e elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"94ec73e\" data-element_type=\"section\" id=\"featured-services\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-81ee2e6\" data-id=\"81ee2e6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b0056e1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b0056e1\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-ad2c522\" data-id=\"ad2c522\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-667c3ef elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"667c3ef\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon elementor-animation-bounce-in\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-warehouse\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-34246dc elementor-widget elementor-widget-heading\" data-id=\"34246dc\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Constructeurs automobiles<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-99fbd25 elementor-widget elementor-widget-text-editor\" data-id=\"99fbd25\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>De la carroserie au ch\u00e2ssis, de l&rsquo;int\u00e9rieur au moteur, traitement des v\u00e9hicules avec SOWAX sur cha\u00eene de montage ou en sortie d&rsquo;usine. <strong><a class=\"scrollto\" href=\"https:\/\/waxoyl.projet-client.com\/en\/#contact\">Nous contacter<\/a><\/strong> pour trouver la solution ad\u00e9quate.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-56f821f\" data-id=\"56f821f\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-62d8d4c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"62d8d4c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-071e279\" data-id=\"071e279\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0a669b4 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"0a669b4\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon elementor-animation-bounce-in\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-store\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4a29e8b elementor-widget elementor-widget-heading\" data-id=\"4a29e8b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Groupes automobiles<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-df267c0 elementor-widget elementor-widget-text-editor\" data-id=\"df267c0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Apport d&rsquo;une valeur ajout\u00e9e aux services des Concessionnaires, revendeurs, marchands de v\u00e9hicules d&rsquo;occasions. <strong><a class=\"scrollto\" href=\"https:\/\/waxoyl.projet-client.com\/en\/#contact\">Nous contacter<\/a> <\/strong>pour satisfaire au mieux vos clients.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-0e19c91\" data-id=\"0e19c91\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e8b0cdf elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e8b0cdf\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-6280d08\" data-id=\"6280d08\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8199e8a elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"8199e8a\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon elementor-animation-bounce-in\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-industry\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d8d54cf elementor-widget elementor-widget-heading\" data-id=\"d8d54cf\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Industries g\u00e9n\u00e9rales<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-12c9e69 elementor-widget elementor-widget-text-editor\" data-id=\"12c9e69\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Leader dans les domaines de l&rsquo;a\u00e9ronautique, du g\u00e9nie civil, de la carrosserie industrielle et des transports, nous vous apportons la solution afin d&rsquo;\u00e9viter la corrosion. <strong><a class=\"scrollto\" href=\"https:\/\/waxoyl.projet-client.com\/en\/#contact\">Nous contacter<\/a><\/strong> pour une expertise personnalis\u00e9e.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9fe14ee elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9fe14ee\" data-element_type=\"section\" id=\"missions\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8f398f7\" data-id=\"8f398f7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0b74973 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"0b74973\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">LES MISSIONS DE SOWAX by SOFDI <\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e372fe2 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"e372fe2\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>SOWAX pour les constructeurs, les groupes automobiles, et les compagnies industrielles<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f84b008 elementor-widget elementor-widget-text-editor\" data-id=\"f84b008\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Les pluies acides, les rayons solaires, l&rsquo;air salin sont des \u00e9l\u00e9ments nocifs qui nuisent de plus en plus <strong>au bon \u00e9tat des machines et des v\u00e9hicules<\/strong>. Alors que la r\u00e9glementation emp\u00eache l&rsquo;utilisation de solvants, fragilisant nos peintures, les exigences quant \u00e0 la dur\u00e9e de vie et <strong>\u00e0 la r\u00e9sistance au temps des mat\u00e9riaux modernes<\/strong> se sont consid\u00e9rablement accrues,<strong> sur terre, en mer et dans l&rsquo;air<\/strong>. SOWAX y satisfait avec des produits, traitements exclusifs et des programmes con\u00e7us sp\u00e9cifiquement pour r\u00e9pondre \u00e0 ces contraintes.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2d56788 elementor-widget elementor-widget-spacer\" data-id=\"2d56788\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-dc5de11 elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"dc5de11\" data-element_type=\"section\" id=\"solutions\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1ade8b0\" data-id=\"1ade8b0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-cd670c4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cd670c4\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-342646a elementor-invisible\" data-id=\"342646a\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:100}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6d0878f elementor-widget elementor-widget-image\" data-id=\"6d0878f\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"614\" src=\"https:\/\/sowax.fr\/wp-content\/uploads\/2024\/03\/Innovation_Light-1024x614.png\" class=\"attachment-large size-large wp-image-12740\" alt=\"\" srcset=\"https:\/\/sowax.fr\/wp-content\/uploads\/2024\/03\/Innovation_Light-1024x614.png 1024w, https:\/\/sowax.fr\/wp-content\/uploads\/2024\/03\/Innovation_Light-300x180.png 300w, https:\/\/sowax.fr\/wp-content\/uploads\/2024\/03\/Innovation_Light-768x461.png 768w, https:\/\/sowax.fr\/wp-content\/uploads\/2024\/03\/Innovation_Light-1536x922.png 1536w, https:\/\/sowax.fr\/wp-content\/uploads\/2024\/03\/Innovation_Light-2048x1229.png 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8e52a9e elementor-view-stacked elementor-absolute icon-border-white elementor-shape-circle elementor-widget elementor-widget-icon\" data-id=\"8e52a9e\" data-element_type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon elementor-animation-pulse\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-microscope\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d69ecef elementor-widget elementor-widget-heading\" data-id=\"d69ecef\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Innovation<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bf0cf2b elementor-widget elementor-widget-text-editor\" data-id=\"bf0cf2b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Depuis 1999, SOFDI lutte contre la corrosion et l&rsquo;alt\u00e9ration des m\u00e9taux.<\/p><p>SOFDI est sp\u00e9cialis\u00e9 dans l&rsquo;\u00e9laboration de <strong>concepts high-tech pour la protection des machines industrielles et des peintures automobiles<\/strong>. Ces produits de haute qualit\u00e9 sont <strong>constamment am\u00e9lior\u00e9s gr\u00e2ce \u00e0 la veille technique et \u00e0 notre d\u00e9partement R&amp;D<\/strong>.<\/p><p>Nos produits sont fabriqu\u00e9s selon les <strong>normes techniques et scientifiques<\/strong> les plus rigoureuses.<\/p><p>Experts dans la lutte contre la corrosion, nous avons \u00e9largi notre champ d&rsquo;application \u00e0 la protection des peintures automobiles soumises aux agressions environnementales.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-9796370 elementor-invisible\" data-id=\"9796370\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:200}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b57ff53 elementor-view-stacked elementor-absolute icon-border-white elementor-shape-circle elementor-widget elementor-widget-icon\" data-id=\"b57ff53\" data-element_type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon elementor-animation-pulse\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-concierge-bell\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b466f5d elementor-widget elementor-widget-image\" data-id=\"b466f5d\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"614\" src=\"https:\/\/sowax.fr\/wp-content\/uploads\/2024\/03\/concession_automobile-1024x614.png\" class=\"attachment-large size-large wp-image-12750\" alt=\"\" srcset=\"https:\/\/sowax.fr\/wp-content\/uploads\/2024\/03\/concession_automobile-1024x614.png 1024w, https:\/\/sowax.fr\/wp-content\/uploads\/2024\/03\/concession_automobile-300x180.png 300w, https:\/\/sowax.fr\/wp-content\/uploads\/2024\/03\/concession_automobile-768x461.png 768w, https:\/\/sowax.fr\/wp-content\/uploads\/2024\/03\/concession_automobile-1536x922.png 1536w, https:\/\/sowax.fr\/wp-content\/uploads\/2024\/03\/concession_automobile-2048x1229.png 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7c1701d elementor-widget elementor-widget-heading\" data-id=\"7c1701d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Services<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-63dc6ff elementor-widget elementor-widget-text-editor\" data-id=\"63dc6ff\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Chaque traitement de protection est appliqu\u00e9 par des <strong>professionnels agr\u00e9\u00e9s et form\u00e9s par SOFDI<\/strong>. Forts d&rsquo;une exp\u00e9rience de plus de 20 ans dans le diagnostic des causes de l&rsquo;oxydation, nos experts sont \u00e0 votre \u00e9coute pour analyser vos besoins.\u00a0<\/p><ul><li><strong>Industriels<\/strong>, nous vous accompagnons et nous vous pr\u00e9conisons les solutions adpat\u00e9es \u00e0 votre activit\u00e9 dans la lutte contre la corrosion, v\u00e9ritable fl\u00e9au industriel.<\/li><li><strong>Concessionnaires<\/strong>, nous formons vos \u00e9quipes de vente &amp; vos pr\u00e9parateurs. Pr\u00e9sents sur tout le territoire national, nous visitons r\u00e9guli\u00e8rement tous nos partenaires concessionnaires et leur offrons ainsi un accompagnement sur mesure.<\/li><\/ul><p><strong><a class=\"scrollto\" href=\"https:\/\/waxoyl.projet-client.com\/en\/#contact\">Contactez-nous<\/a> <\/strong>pour <strong>une solution sur-mesure<\/strong>.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-4bddaea elementor-invisible\" data-id=\"4bddaea\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:300}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f31499b elementor-widget elementor-widget-image\" data-id=\"f31499b\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"614\" src=\"https:\/\/sowax.fr\/wp-content\/uploads\/2024\/03\/Satisfaction-client-1024x614.jpeg\" class=\"attachment-large size-large wp-image-12811\" alt=\"\" srcset=\"https:\/\/sowax.fr\/wp-content\/uploads\/2024\/03\/Satisfaction-client-1024x614.jpeg 1024w, https:\/\/sowax.fr\/wp-content\/uploads\/2024\/03\/Satisfaction-client-300x180.jpeg 300w, https:\/\/sowax.fr\/wp-content\/uploads\/2024\/03\/Satisfaction-client-768x461.jpeg 768w, https:\/\/sowax.fr\/wp-content\/uploads\/2024\/03\/Satisfaction-client-1536x922.jpeg 1536w, https:\/\/sowax.fr\/wp-content\/uploads\/2024\/03\/Satisfaction-client-2048x1229.jpeg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5bbab40 elementor-view-stacked elementor-absolute icon-border-white elementor-shape-circle elementor-widget elementor-widget-icon\" data-id=\"5bbab40\" data-element_type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon elementor-animation-pulse\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-thumbs-up\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c84a048 elementor-widget elementor-widget-heading\" data-id=\"c84a048\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Satisfaction<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-66374f0 elementor-widget elementor-widget-text-editor\" data-id=\"66374f0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p style=\"text-align: center;\">Les traitements SOFDI ont une <strong>r\u00e9putation mondiale<\/strong> en tant que produits utilis\u00e9s dans la fabrication \u00e0 haute valeur ajout\u00e9e.<\/p>\n\n<p style=\"text-align: center;\">Notre exp\u00e9rience et notre expertise tr\u00e8s d\u00e9taill\u00e9e nous conf\u00e8rent une <strong>position de leader<\/strong> en mati\u00e8re de protection contre la corrosion, d&rsquo;entretien de v\u00e9hicules, ainsi qu&rsquo;une meilleure durabilit\u00e9 des machines.<\/p>\n\n<p style=\"text-align: center;\">Aujourd&rsquo;hui, nous offrons une gamme compl\u00e8te de produits destin\u00e9e :<\/p>\n<ul>\n    <li><strong>Secteur automobile<\/strong> <small class=\"text-muted\">(constructeurs de v\u00e9hicules, concessionnaires et marchands de v\u00e9hicules d&rsquo;occasion, ateliers de peinture et de r\u00e9paration&#8230;)<\/small><\/li>\n    <li><strong>Secteur industriel<\/strong> <small class=\"text-muted\">(transport, stockage, maintenance, engins de g\u00e9nie civil, grandes carrosseries industrielles, machines, outillage, pi\u00e8ces, a\u00e9ronautique&#8230;)<\/small><\/li>\n<\/ul>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fc5326e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fc5326e\" data-element_type=\"section\" id=\"benefits\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-48dd3cd\" data-id=\"48dd3cd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-05b73f8 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"05b73f8\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">PARMI NOS NOMBREUX BENEFICES<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ce21b83 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"ce21b83\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Nous assurons une protection pour tous les v\u00e9hicules neufs, d&rsquo;occasion et les mat\u00e9riaux industriels.<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-7fd4696 elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"7fd4696\" data-element_type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;bounceInUp&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-178a78e\" data-id=\"178a78e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c395de4 elementor-position-left elementor-view-default elementor-mobile-position-top elementor-vertical-align-top elementor-widget elementor-widget-icon-box\" data-id=\"c395de4\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon elementor-animation-pulse\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-sun\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tProtection aux rayons UV\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tConserve la couleur gr\u00e2ce aux puissants filtres ultra-violet.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-ad426f8\" data-id=\"ad426f8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9904aa7 elementor-position-left elementor-view-default elementor-mobile-position-top elementor-vertical-align-top elementor-widget elementor-widget-icon-box\" data-id=\"9904aa7\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon elementor-animation-pulse\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-cloud-showers-heavy\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tProtection aux intemp\u00e9ries\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tForme un film protecteur fortement adh\u00e9sif et imperm\u00e9able.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-2c3fc1a\" data-id=\"2c3fc1a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4295fc8 elementor-position-left elementor-view-default elementor-mobile-position-top elementor-vertical-align-top elementor-widget elementor-widget-icon-box\" data-id=\"4295fc8\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon elementor-animation-pulse\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-tint-slash\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tEffet d\u00e9perlant\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tAm\u00e9liore la s\u00e9curit\u00e9 de la conduite par temps de pluie.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-8010aea elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"8010aea\" data-element_type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;bounceInUp&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-a7769bd\" data-id=\"a7769bd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7db2e34 elementor-position-left elementor-view-default elementor-mobile-position-top elementor-vertical-align-top elementor-widget elementor-widget-icon-box\" data-id=\"7db2e34\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon elementor-animation-pulse\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-snowflake\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tProtection au froid et \u00e0 l'air salin\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t\u00c9vite l'oxydation li\u00e9e aux sels d'\u00e9pandage et aux embruns.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-e991f11\" data-id=\"e991f11\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-10a2ca6 elementor-position-left elementor-view-default elementor-mobile-position-top elementor-vertical-align-top elementor-widget elementor-widget-icon-box\" data-id=\"10a2ca6\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon elementor-animation-pulse\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-euro-sign\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tMaintien de la valeur\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tPr\u00e9serve l'aspect neuf du v\u00e9hicule plus longtemps et, par cons\u00e9quent, assure une plus grande valeur de revente.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-9dc02a9\" data-id=\"9dc02a9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5563c02 elementor-position-left elementor-view-default elementor-mobile-position-top elementor-vertical-align-top elementor-widget elementor-widget-icon-box\" data-id=\"5563c02\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon elementor-animation-pulse\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-cogs\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tMaintenance industrielle\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tAtteint facilement les endroits inaccessibles et prolonge la dur\u00e9e de vie de la carrosserie, pi\u00e8ces, outillage...\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-cdf9245 elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"cdf9245\" data-element_type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;bounceInUp&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-91e36d2\" data-id=\"91e36d2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b57ff0f elementor-position-left elementor-view-default elementor-mobile-position-top elementor-vertical-align-top elementor-widget elementor-widget-icon-box\" data-id=\"b57ff0f\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon elementor-animation-pulse\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-fill-drip\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tProtection contre la salissure\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tFacilite l'\u00e9limination de la salet\u00e9, des insectes et autres mati\u00e8res agressives.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-add91f3\" data-id=\"add91f3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f4ca6f6 elementor-position-left elementor-view-default elementor-mobile-position-top elementor-vertical-align-top elementor-widget elementor-widget-icon-box\" data-id=\"f4ca6f6\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon elementor-animation-pulse\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-gem\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tEffet haute brillance\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tGarde assur\u00e9ment la profonde brillance.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-cdd6805\" data-id=\"cdd6805\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c5f9572 elementor-position-left elementor-view-default elementor-mobile-position-top elementor-vertical-align-top elementor-widget elementor-widget-icon-box\" data-id=\"c5f9572\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon elementor-animation-pulse\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-piggy-bank\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t\u00c9conomie quotidienne\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t\u00c9conomie de temps en mati\u00e8re de nettoyage et pr\u00e9servation de la valeur des v\u00e9hicules et mat\u00e9riaux.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bd1eeb6 elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"bd1eeb6\" data-element_type=\"section\" id=\"call-to-action\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cf62a01\" data-id=\"cf62a01\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9491dc7 elementor-widget elementor-widget-heading\" data-id=\"9491dc7\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><span>D\u00e9couvrir encore plus d'avantages<\/span><\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2608c21 elementor-widget elementor-widget-text-editor\" data-id=\"2608c21\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Nous contacter pour en savoir plus sur nos traitements exclusifs et trouver la solution ad\u00e9quate.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eb28107 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"eb28107\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"\/fr\/#contact\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Nous contacter<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5dc858e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5dc858e\" data-element_type=\"section\" id=\"treatments\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-aac00af\" data-id=\"aac00af\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e04ebc6 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"e04ebc6\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-large\">NOS TRAITEMENTS EXCLUSIFS<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-93c8dbe elementor-widget elementor-widget-post-filter\" data-id=\"93c8dbe\" data-element_type=\"widget\" data-widget_type=\"post-filter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n    <div>\n      <ul class=\"elementor-portfolio__filters cat-filter-for-treatment-wrap\" id=\"filter-category-93c8dbe\" data-hide-empty=\"\">\n        <li\n    class=\"super-cat-post-filter elementor-portfolio__filter elementor-active\"\n    data-term=\"\"\n    data-container=\"filter-category-93c8dbe\"\n    data-posts=\"treatment-wrap\">\n    Tous\n    <\/li>        <li\n      class=\"super-cat-post-filter elementor-portfolio__filter\"\n      data-term=\"category-anti-corrosion\"\n      data-container=\"filter-category-93c8dbe\"\n      data-posts=\"treatment-wrap\">\n      Anti corrosion\n      <\/li><li\n      class=\"super-cat-post-filter elementor-portfolio__filter\"\n      data-term=\"category-entretien-interieur-exterieur\"\n      data-container=\"filter-category-93c8dbe\"\n      data-posts=\"treatment-wrap\">\n      Entretien int\u00e9rieur \/ ext\u00e9rieur\n      <\/li><li\n      class=\"super-cat-post-filter elementor-portfolio__filter\"\n      data-term=\"category-exterieur\"\n      data-container=\"filter-category-93c8dbe\"\n      data-posts=\"treatment-wrap\">\n      Ext\u00e9rieur\n      <\/li><li\n      class=\"super-cat-post-filter elementor-portfolio__filter\"\n      data-term=\"category-interieur\"\n      data-container=\"filter-category-93c8dbe\"\n      data-posts=\"treatment-wrap\">\n      Int\u00e9rieur\n      <\/li><li\n      class=\"super-cat-post-filter elementor-portfolio__filter\"\n      data-term=\"category-maintenance\"\n      data-container=\"filter-category-93c8dbe\"\n      data-posts=\"treatment-wrap\">\n      Maintenance\n      <\/li><li\n      class=\"super-cat-post-filter elementor-portfolio__filter\"\n      data-term=\"category-scellement-de-peinture\"\n      data-container=\"filter-category-93c8dbe\"\n      data-posts=\"treatment-wrap\">\n      Scellement de peinture\n      <\/li><li\n      class=\"super-cat-post-filter elementor-portfolio__filter\"\n      data-term=\"category-transport-stockage\"\n      data-container=\"filter-category-93c8dbe\"\n      data-posts=\"treatment-wrap\">\n      Transport &amp; stockage\n      <\/li>      <\/ul>\n    <\/div>\n\n    \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9b03778 elementor-grid-3 elementor-grid-tablet-2 elementor-grid-mobile-1 elementor-posts--thumbnail-top elementor-widget elementor-widget-posts\" data-id=\"9b03778\" data-element_type=\"widget\" id=\"treatment-wrap\" data-settings=\"{&quot;classic_columns&quot;:&quot;3&quot;,&quot;classic_columns_tablet&quot;:&quot;2&quot;,&quot;classic_columns_mobile&quot;:&quot;1&quot;,&quot;classic_row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:35,&quot;sizes&quot;:[]},&quot;classic_row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;classic_row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"posts.classic\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-posts-container elementor-posts elementor-posts--skin-classic elementor-grid\">\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-2124 treatment type-treatment status-publish has-post-thumbnail hentry category-exterieur category-scellement-de-peinture\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/sowax.fr\/fr\/treatment\/sowax-ceramique\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"150\" src=\"https:\/\/sowax.fr\/wp-content\/uploads\/2024\/03\/Voiture_Noir-300x150.jpeg\" class=\"attachment-medium size-medium wp-image-13036\" alt=\"\" srcset=\"https:\/\/sowax.fr\/wp-content\/uploads\/2024\/03\/Voiture_Noir-300x150.jpeg 300w, https:\/\/sowax.fr\/wp-content\/uploads\/2024\/03\/Voiture_Noir-1024x512.jpeg 1024w, https:\/\/sowax.fr\/wp-content\/uploads\/2024\/03\/Voiture_Noir-768x384.jpeg 768w, https:\/\/sowax.fr\/wp-content\/uploads\/2024\/03\/Voiture_Noir-1536x768.jpeg 1536w, https:\/\/sowax.fr\/wp-content\/uploads\/2024\/03\/Voiture_Noir-2048x1024.jpeg 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/sowax.fr\/fr\/treatment\/sowax-ceramique\/\" >\n\t\t\t\tSowax C\u00e9ramique\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Protection de la peinture <\/p>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-256 treatment type-treatment status-publish has-post-thumbnail hentry\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/sowax.fr\/fr\/treatment\/sowax-plus\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/sowax.fr\/wp-content\/uploads\/2024\/03\/Voiture_rouge_neutre-300x200.jpeg\" class=\"attachment-medium size-medium wp-image-12957\" alt=\"\" srcset=\"https:\/\/sowax.fr\/wp-content\/uploads\/2024\/03\/Voiture_rouge_neutre-300x200.jpeg 300w, https:\/\/sowax.fr\/wp-content\/uploads\/2024\/03\/Voiture_rouge_neutre-1024x683.jpeg 1024w, https:\/\/sowax.fr\/wp-content\/uploads\/2024\/03\/Voiture_rouge_neutre-768x512.jpeg 768w, https:\/\/sowax.fr\/wp-content\/uploads\/2024\/03\/Voiture_rouge_neutre-1536x1025.jpeg 1536w, https:\/\/sowax.fr\/wp-content\/uploads\/2024\/03\/Voiture_rouge_neutre-2048x1367.jpeg 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/sowax.fr\/fr\/treatment\/sowax-plus\/\" >\n\t\t\t\tSowax Plus\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Nettoyage, protection, et entretien complet pour votre voiture, \u00e0 l&rsquo;int\u00e9rieur et \u00e0 l&rsquo;ext\u00e9rieur.<\/p>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bed6b47 elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"bed6b47\" data-element_type=\"section\" id=\"numbers\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-859c586\" data-id=\"859c586\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fd1de42 elementor-widget elementor-widget-heading\" data-id=\"fd1de42\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-large\">SOWAX EN QUELQUES CHIFFRES<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7e47e0b elementor-widget elementor-widget-text-editor\" data-id=\"7e47e0b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Les faits valent souvent mieux que de beaux discours<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6ecab3b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6ecab3b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-0da6c95\" data-id=\"0da6c95\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4bd5a81 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"4bd5a81\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon elementor-animation-pulse\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-store\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cd8abd8 elementor-widget elementor-widget-counter\" data-id=\"cd8abd8\" data-element_type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">Plus de 3000 concessions, toutes marques, fid\u00e8les \u00e0 SOFDI en Europe.<\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"3000\" data-from-value=\"0\">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\"><\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-8bd5619\" data-id=\"8bd5619\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4769a46 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"4769a46\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon elementor-animation-pulse\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-birthday-cake\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6a5eb89 elementor-widget elementor-widget-counter\" data-id=\"6a5eb89\" data-element_type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">Depuis plus de 20 ans SOFDI est Leader dans la protection de la corrosion<\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"1999\" data-from-value=\"0\">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\"><\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-91d5063\" data-id=\"91d5063\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c2a3894 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"c2a3894\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon elementor-animation-pulse\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-industry\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-862e8c0 elementor-widget elementor-widget-counter\" data-id=\"862e8c0\" data-element_type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">C'est le nombre de grands groupes que nous accompagnons et il augmente chaque jour.<\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"60\" data-from-value=\"0\">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\"><\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-6e1eaa0\" data-id=\"6e1eaa0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-32bbc13 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"32bbc13\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon elementor-animation-pulse\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-tachometer-alt\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c482d6b elementor-widget elementor-widget-counter\" data-id=\"c482d6b\" data-element_type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">2 000 000 v\u00e9hicules trait\u00e9s par par le r\u00e9seau des concessionnaires SOFDI<\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"2\" data-from-value=\"0\">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\">M<\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8fc178f elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"8fc178f\" data-element_type=\"section\" id=\"uses\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9165f2c\" data-id=\"9165f2c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4fc1205 elementor-widget elementor-widget-heading\" data-id=\"4fc1205\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">QUELQUES UTILISATIONS<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-260abff elementor-widget elementor-widget-text-editor\" data-id=\"260abff\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Les traitements SOWAX s&rsquo;adaptent \u00e0 vos besoins<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9f599e4 elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"9f599e4\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;6&quot;,&quot;slides_to_scroll&quot;:&quot;6&quot;,&quot;navigation&quot;:&quot;dots&quot;,&quot;lazyload&quot;:&quot;yes&quot;,&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:30,&quot;sizes&quot;:[]},&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500,&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 of 15\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/sowax.fr\/wp-content\/uploads\/2023\/10\/Yacht-scaled-e1698049749521-300x200.jpeg\" alt=\"Bateau \/ Yacht\" \/><div class=\"swiper-lazy-preloader\"><\/div><figcaption class=\"elementor-image-carousel-caption\">Bateau \/ Yacht<\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 of 15\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/sowax.fr\/wp-content\/uploads\/2023\/10\/Bus-300x200.jpg\" alt=\"Car \/ Bus \/ Autobus \/ Autocar\" \/><div class=\"swiper-lazy-preloader\"><\/div><figcaption class=\"elementor-image-carousel-caption\">Car \/ Bus \/ Autobus \/ Autocar<\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 of 15\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/sowax.fr\/wp-content\/uploads\/2023\/10\/Closeup-300x200.jpg\" alt=\"Voiture\" \/><div class=\"swiper-lazy-preloader\"><\/div><figcaption class=\"elementor-image-carousel-caption\">Voiture<\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 of 15\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/sowax.fr\/wp-content\/uploads\/2023\/10\/Bulldozer-300x200.jpg\" alt=\"G\u00e9nie civil \/ Engin de chantier\" \/><div class=\"swiper-lazy-preloader\"><\/div><figcaption class=\"elementor-image-carousel-caption\">G\u00e9nie civil \/ Engin de chantier<\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 of 15\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/sowax.fr\/wp-content\/uploads\/2023\/10\/Zone-industriel-300x200.jpg\" alt=\"Usine \/ Hangar \/ Entrep\u00f4t\" \/><div class=\"swiper-lazy-preloader\"><\/div><figcaption class=\"elementor-image-carousel-caption\">Usine \/ Hangar \/ Entrep\u00f4t<\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 of 15\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/sowax.fr\/wp-content\/uploads\/2023\/10\/Avion-300x200.jpg\" alt=\"Avion \/ Jet\" \/><div class=\"swiper-lazy-preloader\"><\/div><figcaption class=\"elementor-image-carousel-caption\">Avion \/ Jet<\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 of 15\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/sowax.fr\/wp-content\/uploads\/2023\/10\/Camion-1-300x200.jpg\" alt=\"Poids lourd \/ Camion \/ Semi-remorque\" \/><div class=\"swiper-lazy-preloader\"><\/div><figcaption class=\"elementor-image-carousel-caption\">Poids lourd \/ Camion \/ Semi-remorque<\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 of 15\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/sowax.fr\/wp-content\/uploads\/2023\/10\/Machine-industrielle-300x200.jpg\" alt=\"Pi\u00e8ces \/ Outillage \/ Maintenance\" \/><div class=\"swiper-lazy-preloader\"><\/div><figcaption class=\"elementor-image-carousel-caption\">Pi\u00e8ces \/ Outillage \/ Maintenance<\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 of 15\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/sowax.fr\/wp-content\/uploads\/2023\/10\/Train-300x200.jpg\" alt=\"R\u00e9seau ferroviaire \/ Train \/ Tramway \/ M\u00e9tro\" \/><div class=\"swiper-lazy-preloader\"><\/div><figcaption class=\"elementor-image-carousel-caption\">R\u00e9seau ferroviaire \/ Train \/ Tramway \/ M\u00e9tro<\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"10 of 15\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/sowax.fr\/wp-content\/uploads\/2023\/10\/Caterpillars_parking-300x200.jpeg\" alt=\"Transport \/ Stockage\" \/><div class=\"swiper-lazy-preloader\"><\/div><figcaption class=\"elementor-image-carousel-caption\">Transport \/ Stockage<\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"11 of 15\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/sowax.fr\/wp-content\/uploads\/2023\/10\/Camionnette-300x200.jpg\" alt=\"Camionnette \/ Fourgonnette \/ Utilitaire\" \/><div class=\"swiper-lazy-preloader\"><\/div><figcaption class=\"elementor-image-carousel-caption\">Camionnette \/ Fourgonnette \/ Utilitaire<\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"12 of 15\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/sowax.fr\/wp-content\/uploads\/2023\/10\/Eolienne-300x200.jpeg\" alt=\"Eolienne \/ Couronne\" \/><div class=\"swiper-lazy-preloader\"><\/div><figcaption class=\"elementor-image-carousel-caption\">Eolienne \/ Couronne<\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"13 of 15\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/sowax.fr\/wp-content\/uploads\/2023\/10\/Satellite-300x200.jpg\" alt=\"Satellite\" \/><div class=\"swiper-lazy-preloader\"><\/div><figcaption class=\"elementor-image-carousel-caption\">Satellite<\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"14 of 15\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/sowax.fr\/wp-content\/uploads\/2023\/10\/Plate-forme-petroliere-300x200.jpg\" alt=\"Plate-forme p\u00e9troli\u00e8re\" \/><div class=\"swiper-lazy-preloader\"><\/div><figcaption class=\"elementor-image-carousel-caption\">Plate-forme p\u00e9troli\u00e8re<\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"15 of 15\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/sowax.fr\/wp-content\/uploads\/2023\/10\/Grands_reservoirs-300x200.jpg\" alt=\"Grands r\u00e9servoirs\" \/><div class=\"swiper-lazy-preloader\"><\/div><figcaption class=\"elementor-image-carousel-caption\">Grands r\u00e9servoirs<\/figcaption><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9cfff43 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9cfff43\" data-element_type=\"section\" id=\"warranties\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b837e2c\" data-id=\"b837e2c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-502cecb elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"502cecb\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">GARANTIES FOURNISSEUR<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-957095c elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"957095c\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Nous garantissons les traitements &#8230;<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-eb26017 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"eb26017\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-845b3c1 elementor-invisible\" data-id=\"845b3c1\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;bounceInLeft&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-72a9ef9 elementor-position-left elementor-view-default elementor-mobile-position-top elementor-vertical-align-top elementor-widget elementor-widget-icon-box\" data-id=\"72a9ef9\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon elementor-animation-\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-award\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tContr\u00f4le de garantie du client final\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-256ca2c elementor-widget elementor-widget-text-editor\" data-id=\"256ca2c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>V\u00e9rifier la Garantie SOWAX Scellement de peinture.<\/p><p>Pour contr\u00f4ler l&rsquo;\u00e9tat de la garantie SOWAX Gard \u00e0 tout moment.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e51a208 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"e51a208\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6MTMzODQsInRvZ2dsZSI6ZmFsc2V9\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">V\u00e9rifier ma garantie<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-d5aefe0 elementor-invisible\" data-id=\"d5aefe0\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;bounceInRight&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5d76ae7 elementor-position-left elementor-view-default elementor-mobile-position-top elementor-vertical-align-top elementor-widget elementor-widget-icon-box\" data-id=\"5d76ae7\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon elementor-animation-\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-certificate\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tEnregistrement de garanties par concessionnaires\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-be2a71a elementor-widget elementor-widget-text-editor\" data-id=\"be2a71a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p class=\"description\">Pour enregistrer les garanties des clients, veuillez cliquer sur le bouton ci-dessous.<\/p><p class=\"description\">Utiliser cette option pour l&rsquo;enregistrement de SOWAX Gard \u00e0 tout moment.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0f3382d elementor-align-center elementor-widget elementor-widget-button\" data-id=\"0f3382d\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/sofdi-group-extranet.com\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Connectez-vous \u00e0 votre compte<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-58203e0 elementor-widget elementor-widget-heading\" data-id=\"58203e0\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">PLUS QU'UNE GARANTIE, UNE ETHIQUE<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a16fb08 elementor-widget elementor-widget-text-editor\" data-id=\"a16fb08\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Nous pr\u00eatons une attention rigoureuse \u00e0 notre charte qualit\u00e9.<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-460a7c2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"460a7c2\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-73e64fb elementor-invisible\" data-id=\"73e64fb\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;bounceInLeft&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c505697 elementor-position-left elementor-view-default elementor-mobile-position-top elementor-vertical-align-top elementor-widget elementor-widget-icon-box\" data-id=\"c505697\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon elementor-animation-\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-graduation-cap\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tFormation des concessionnaires partenaires agr\u00e9\u00e9s\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-77de312 elementor-widget elementor-widget-text-editor\" data-id=\"77de312\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Nous certifions que le personnel sp\u00e9cialis\u00e9 \u00e0 la pr\u00e9paration des v\u00e9hicules de votre concession a re\u00e7u la formation \u00e0 l&rsquo;application des concepts SOWAX.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-d0bdf07 elementor-invisible\" data-id=\"d0bdf07\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;bounceInRight&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-231fe35 elementor-position-left elementor-view-default elementor-mobile-position-top elementor-vertical-align-top elementor-widget elementor-widget-icon-box\" data-id=\"231fe35\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon elementor-animation-\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-leaf\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tGarantie environnementale\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8f6bf72 elementor-widget elementor-widget-text-editor\" data-id=\"8f6bf72\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Les produits SOWAX ne nuisent pas \u00e0 l&rsquo;environnement et ne contiennent pas de silicone.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-db23fd0 elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"db23fd0\" data-element_type=\"section\" id=\"contact\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-97d8110\" data-id=\"97d8110\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c9861f0 elementor-widget elementor-widget-heading\" data-id=\"c9861f0\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">CONTACTEZ-NOUS<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-50f74fe elementor-widget elementor-widget-text-editor\" data-id=\"50f74fe\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Nous contacter pour plus de d\u00e9tails sur les solutions de traitements SOWAX<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3674e1b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3674e1b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-409006c\" data-id=\"409006c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a81fe50 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"a81fe50\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon elementor-animation-pop\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-address-book\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-efd8056 elementor-widget elementor-widget-heading\" data-id=\"efd8056\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Adresse<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8d37b6e elementor-widget elementor-widget-text-editor\" data-id=\"8d37b6e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>27, Rue Foucher Lepelletier<br \/>92130 Issy-les-Moulineaux<br \/>France<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-ee060bf\" data-id=\"ee060bf\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c3abb3b elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"c3abb3b\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon elementor-animation-pop\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-phone\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d20a26b elementor-widget elementor-widget-heading\" data-id=\"d20a26b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">T\u00e9l\u00e9phone<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ec2c9c4 elementor-widget elementor-widget-text-editor\" data-id=\"ec2c9c4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><a href=\"tel:+33146620971\">+33 (0)1 46 62 09 71<\/a><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-6df82c8 eael-contact-form-7-button-custom elementor-widget elementor-widget-eael-contact-form-7\" data-id=\"6df82c8\" data-element_type=\"widget\" data-widget_type=\"eael-contact-form-7.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"eael-contact-form-7-wrapper\">\n                <div class=\"eael-contact-form eael-contact-form-7 eael-contact-form-6df82c8 labels-hide placeholder-show eael-contact-form-align-default\">\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f571-o1\" lang=\"fr-FR\" dir=\"ltr\" data-wpcf7-id=\"571\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/fr\/wp-json\/wp\/v2\/pages\/906#wpcf7-f571-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Formulaire de contact\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"571\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.5\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"fr_FR\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f571-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<div class=\"elementor-form-fields-wrapper\">\n\t<div class=\"elementor-column elementor-col-50\">\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" minlength=\"4\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Votre nom et soci\u00e9t\u00e9\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"elementor-column elementor-col-50\">\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Votre email\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"elementor-column elementor-col-100\">\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-subject\"><input size=\"40\" maxlength=\"400\" minlength=\"8\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Sujet\" value=\"\" type=\"text\" name=\"your-subject\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"elementor-column elementor-col-100\">\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" minlength=\"4\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" placeholder=\"Votre message\" name=\"your-message\"><\/textarea><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"elementor-column elementor-col-100\">\n\t\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Envoyer votre message\" \/>\n\t\t<\/p>\n\t<\/div>\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n<\/div>\n            <\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b722fea elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b722fea\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4c1ac5d\" data-id=\"4c1ac5d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-77ab70d elementor-widget elementor-widget-form-poster\" data-id=\"77ab70d\" data-element_type=\"widget\" data-widget_type=\"form-poster.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n        <script type='text\/javascript'>\n        document.addEventListener(\"DOMContentLoaded\", function(event) {\n            \/* The ID assigned to the form widget via Elementor *\/\n            var formID = \"#\";\n            \/* The URL to which you want to send the data *\/\n            var actionURL = \"\";\n            var superGattoID = \"#form-super-gatto-for-\";\n\n            var $jq = jQuery.noConflict();\n            $jq(superGattoID).html($jq(formID).html());\n            $jq(superGattoID).attr(\"class\", $jq(formID).attr(\"class\"));\n            $jq(formID).hide();\n            $jq(superGattoID + \" form\").attr(\"action\", actionURL);\n            $jq(superGattoID + \" form\").find('input, textarea, select').each(function(){\n                var matches = $jq(this).attr(\"name\").match(\/form_fields\\[(.*?)\\]\/);\n                if (matches) {\n                    var submatch = matches[1];\n                     submatch = submatch.replace(\/\\_[0-9]+\/g, function(x){return \"[\"+x.replace(\"_\", \"\")+\"]\";});                     $jq(this).attr(\"name\", submatch);\n                }else{\n                    $jq(this).remove();\n                }\n                var cls=$jq(this).attr(\"class\");\n                if ( cls && cls.match(\/flatpickr\/) ){\n                    $jq(this).flatpickr();\n                }\n            });\n            \/\/ $jq(superGattoID + \" form\").submit(function(){\n            \/\/     $jq(this).find('input, textarea, select').each(function(){\n            \/\/         \/* SET THE COOKIE *\/\n            \/\/         var name = \"supercat_form_\" + $jq(this).attr(\"name\");\n            \/\/         var value = $jq(this).val();\n            \/\/         var expires = \"\";\n            \/\/         document.cookie = encodeURIComponent(name) + \"=\" + encodeURIComponent(value) + expires + \"; path=\/\";\n            \/\/     });\n            \/\/ });\n        });\n        <\/script>\n        <div id=\"form-super-gatto-for-\"><\/div>\n        \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Exclusivement pour des professionnelspar des professionnels Constructeurs automobiles, concessionnaires automobiles ou dans l&rsquo;industrie en g\u00e9n\u00e9ral, SOWAX est fait pour vous ! Commencez votre visiteScellement de peinturehaute brillance Nos traitements conf\u00e8rent \u00e0 la couche de peinture des voitures, un bouclier \u00e0 haute brillance pratiquement inviolable D\u00e9couvrez nos traitements Previous slide Next slide Sp\u00e9cialis\u00e9e dans la protection [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-906","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Accueil | SOWAX<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sowax.fr\/fr\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Accueil | SOWAX\" \/>\n<meta property=\"og:description\" content=\"Exclusivement pour des professionnelspar des professionnels Constructeurs automobiles, concessionnaires automobiles ou dans l&rsquo;industrie en g\u00e9n\u00e9ral, SOWAX est fait pour vous ! Commencez votre visiteScellement de peinturehaute brillance Nos traitements conf\u00e8rent \u00e0 la couche de peinture des voitures, un bouclier \u00e0 haute brillance pratiquement inviolable D\u00e9couvrez nos traitements Previous slide Next slide Sp\u00e9cialis\u00e9e dans la protection [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sowax.fr\/fr\/\" \/>\n<meta property=\"og:site_name\" content=\"SOWAX\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-30T04:21:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sowax.fr\/wp-content\/uploads\/2024\/03\/Innovation_Light-1024x614.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"14 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sowax.fr\\\/fr\\\/\",\"url\":\"https:\\\/\\\/sowax.fr\\\/fr\\\/\",\"name\":\"Accueil | SOWAX\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sowax.fr\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sowax.fr\\\/fr\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sowax.fr\\\/fr\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sowax.fr\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Innovation_Light-1024x614.png\",\"datePublished\":\"2022-04-11T08:05:51+00:00\",\"dateModified\":\"2024-08-30T04:21:14+00:00\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sowax.fr\\\/fr\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/sowax.fr\\\/fr\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sowax.fr\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Innovation_Light-1024x614.png\",\"contentUrl\":\"https:\\\/\\\/sowax.fr\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Innovation_Light-1024x614.png\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sowax.fr\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/sowax.fr\\\/fr\\\/\",\"name\":\"SOWAX\",\"description\":\"By SOFDI\",\"publisher\":{\"@id\":\"https:\\\/\\\/sowax.fr\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sowax.fr\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sowax.fr\\\/fr\\\/#organization\",\"name\":\"SOWAX\",\"url\":\"https:\\\/\\\/sowax.fr\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/sowax.fr\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/sowax.fr\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-cropped-Sowax-Rouge.png\",\"contentUrl\":\"https:\\\/\\\/sowax.fr\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-cropped-Sowax-Rouge.png\",\"width\":2742,\"height\":904,\"caption\":\"SOWAX\"},\"image\":{\"@id\":\"https:\\\/\\\/sowax.fr\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Accueil | SOWAX","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sowax.fr\/fr\/","og_locale":"fr_FR","og_type":"article","og_title":"Accueil | SOWAX","og_description":"Exclusivement pour des professionnelspar des professionnels Constructeurs automobiles, concessionnaires automobiles ou dans l&rsquo;industrie en g\u00e9n\u00e9ral, SOWAX est fait pour vous ! Commencez votre visiteScellement de peinturehaute brillance Nos traitements conf\u00e8rent \u00e0 la couche de peinture des voitures, un bouclier \u00e0 haute brillance pratiquement inviolable D\u00e9couvrez nos traitements Previous slide Next slide Sp\u00e9cialis\u00e9e dans la protection [&hellip;]","og_url":"https:\/\/sowax.fr\/fr\/","og_site_name":"SOWAX","article_modified_time":"2024-08-30T04:21:14+00:00","og_image":[{"url":"https:\/\/sowax.fr\/wp-content\/uploads\/2024\/03\/Innovation_Light-1024x614.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"14 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/sowax.fr\/fr\/","url":"https:\/\/sowax.fr\/fr\/","name":"Accueil | SOWAX","isPartOf":{"@id":"https:\/\/sowax.fr\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sowax.fr\/fr\/#primaryimage"},"image":{"@id":"https:\/\/sowax.fr\/fr\/#primaryimage"},"thumbnailUrl":"https:\/\/sowax.fr\/wp-content\/uploads\/2024\/03\/Innovation_Light-1024x614.png","datePublished":"2022-04-11T08:05:51+00:00","dateModified":"2024-08-30T04:21:14+00:00","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sowax.fr\/fr\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/sowax.fr\/fr\/#primaryimage","url":"https:\/\/sowax.fr\/wp-content\/uploads\/2024\/03\/Innovation_Light-1024x614.png","contentUrl":"https:\/\/sowax.fr\/wp-content\/uploads\/2024\/03\/Innovation_Light-1024x614.png"},{"@type":"WebSite","@id":"https:\/\/sowax.fr\/fr\/#website","url":"https:\/\/sowax.fr\/fr\/","name":"SOWAX","description":"By SOFDI","publisher":{"@id":"https:\/\/sowax.fr\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sowax.fr\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/sowax.fr\/fr\/#organization","name":"SOWAX","url":"https:\/\/sowax.fr\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/sowax.fr\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/sowax.fr\/wp-content\/uploads\/2024\/02\/cropped-cropped-Sowax-Rouge.png","contentUrl":"https:\/\/sowax.fr\/wp-content\/uploads\/2024\/02\/cropped-cropped-Sowax-Rouge.png","width":2742,"height":904,"caption":"SOWAX"},"image":{"@id":"https:\/\/sowax.fr\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/sowax.fr\/fr\/wp-json\/wp\/v2\/pages\/906","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sowax.fr\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/sowax.fr\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/sowax.fr\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sowax.fr\/fr\/wp-json\/wp\/v2\/comments?post=906"}],"version-history":[{"count":1292,"href":"https:\/\/sowax.fr\/fr\/wp-json\/wp\/v2\/pages\/906\/revisions"}],"predecessor-version":[{"id":13424,"href":"https:\/\/sowax.fr\/fr\/wp-json\/wp\/v2\/pages\/906\/revisions\/13424"}],"wp:attachment":[{"href":"https:\/\/sowax.fr\/fr\/wp-json\/wp\/v2\/media?parent=906"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}